{"id":9312,"date":"2022-01-23T06:43:53","date_gmt":"2022-01-23T14:43:53","guid":{"rendered":"https:\/\/ahrefs.com\/blog\/es\/?p=9312"},"modified":"2023-10-09T09:41:36","modified_gmt":"2023-10-09T17:41:36","slug":"crear-estrategia-go-to-market","status":"publish","type":"post","link":"https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/","title":{"rendered":"C\u00f3mo crear una estrategia Go-to-Market en 8&nbsp;pasos"},"content":{"rendered":"<div class=\"intro-txt\">La mayor\u00eda de productos nuevos falla\u2014todos lo hemos o\u00eddo. Pero cuanto mejor prepares tu producto y a ti mismo para el lanzamiento, m\u00e1s probabilidades tendr\u00e1s de escapar de esta estad\u00edstica descorazonadora.<\/div>\n<p>La estrategia de <em>go-to-market<\/em>(estrategia para salir al mercado) es <em>el <\/em>m\u00e9todo para darte luz verde para presentar un nuevo producto y hacer cualquier cambio significativo mientras haya tiempo.<\/p>\n<p>En este art\u00edculo aprender\u00e1s:<\/p>\n<ul>\n<li><a href=\"#que-es-estrategia-go-to-market\">Qu\u00e9 es una estrategia go-to-market (GTM)<\/a><\/li>\n<li><a href=\"#estrategia-gtm-vs-estrategia-de-marketing-vs-plan-de-negocio\">Diferencias entre una estrategia GTM, estrategia de marketing y plan de negocio<\/a><\/li>\n<li><a href=\"#por-que-es-importante\">La importancia de tener una estrategia GTM<\/a><\/li>\n<li><a href=\"#como-crear-estrategia-go-to-market\">C\u00f3mo crear una estrategia go-to-market<\/a><\/li>\n<\/ul>\n<div class=\"post-nav-link clearfix\" id=\"section1\"><a class=\"subhead-anchor\" data-tip=\"tooltip__copielink\" rel=\"#section1\"><svg width=\"19\" height=\"19\" viewBox=\"0 0 14 14\" style><g fill=\"none\" fill-rule=\"evenodd\"><path d=\"M0 0h14v14H0z\" \/><path d=\"M7.45 9.887l-1.62 1.621c-.92.92-2.418.92-3.338 0a2.364 2.364 0 0 1 0-3.339l1.62-1.62-1.273-1.272-1.62 1.62a4.161 4.161 0 1 0 5.885 5.884l1.62-1.62L7.45 9.886zM5.527 5.135L7.17 3.492c.92-.92 2.418-.92 3.339 0 .92.92.92 2.418 0 3.339L8.866 8.473l1.272 1.273 1.644-1.643A4.161 4.161 0 1 0 5.897 2.22L4.254 3.863l1.272 1.272zm-.66 3.998a.749.749 0 0 1 0-1.06l2.208-2.206a.749.749 0 1 1 1.06 1.06L5.928 9.133a.75.75 0 0 1-1.061 0z\" style \/><\/g><\/svg><\/a><div class=\"link-text\" data-anchor=\"\u00bfQu\u00e9 es una estrategia go-to-market (GTM)?\" data-section=\"que-es-estrategia-go-to-market\">\n<h2>\u00bfQu\u00e9 es una estrategia go-to-market (GTM)?<\/h2>\n<\/div><\/div>\n<p>Una estrategia go-to-market (GTM) es el plan de una empresa para llevar un nuevo producto o servicio al mercado. B\u00e1sicamente, identifica qu\u00e9 ofrecer\u00e1s, a qu\u00e9 mercado, a qu\u00e9 precio, c\u00f3mo lo ofrecer\u00e1s y qu\u00e9 se necesita a nivel operativo para lanzar el producto\/servicio.<\/p>\n<div class=\"post-nav-link clearfix\" id=\"section1\"><a class=\"subhead-anchor\" data-tip=\"tooltip__copielink\" rel=\"#section1\"><svg width=\"19\" height=\"19\" viewBox=\"0 0 14 14\" style><g fill=\"none\" fill-rule=\"evenodd\"><path d=\"M0 0h14v14H0z\" \/><path d=\"M7.45 9.887l-1.62 1.621c-.92.92-2.418.92-3.338 0a2.364 2.364 0 0 1 0-3.339l1.62-1.62-1.273-1.272-1.62 1.62a4.161 4.161 0 1 0 5.885 5.884l1.62-1.62L7.45 9.886zM5.527 5.135L7.17 3.492c.92-.92 2.418-.92 3.339 0 .92.92.92 2.418 0 3.339L8.866 8.473l1.272 1.273 1.644-1.643A4.161 4.161 0 1 0 5.897 2.22L4.254 3.863l1.272 1.272zm-.66 3.998a.749.749 0 0 1 0-1.06l2.208-2.206a.749.749 0 1 1 1.06 1.06L5.928 9.133a.75.75 0 0 1-1.061 0z\" style \/><\/g><\/svg><\/a><div class=\"link-text\" data-anchor=\"Estrategia GTM vs. estrategia de marketing vs. plan de negocio\" data-section=\"estrategia-gtm-vs-estrategia-de-marketing-vs-plan-de-negocio\">\n<h2>Estrategia GTM vs. estrategia de marketing vs. plan de negocio<\/h2>\n<\/div><\/div>\n<p>Estos t\u00e9rminos se suelen usar de forma intercambiable a pesar de no significar lo mismo. Aqu\u00ed va una comparativa r\u00e1pida de una estrategia de go-to-market, una estrategia de marketing y un plan de negocio:<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/Untitled-22.jpg\"><\/p>\n<div class=\"post-nav-link clearfix\" id=\"section1\"><a class=\"subhead-anchor\" data-tip=\"tooltip__copielink\" rel=\"#section1\"><svg width=\"19\" height=\"19\" viewBox=\"0 0 14 14\" style><g fill=\"none\" fill-rule=\"evenodd\"><path d=\"M0 0h14v14H0z\" \/><path d=\"M7.45 9.887l-1.62 1.621c-.92.92-2.418.92-3.338 0a2.364 2.364 0 0 1 0-3.339l1.62-1.62-1.273-1.272-1.62 1.62a4.161 4.161 0 1 0 5.885 5.884l1.62-1.62L7.45 9.886zM5.527 5.135L7.17 3.492c.92-.92 2.418-.92 3.339 0 .92.92.92 2.418 0 3.339L8.866 8.473l1.272 1.273 1.644-1.643A4.161 4.161 0 1 0 5.897 2.22L4.254 3.863l1.272 1.272zm-.66 3.998a.749.749 0 0 1 0-1.06l2.208-2.206a.749.749 0 1 1 1.06 1.06L5.928 9.133a.75.75 0 0 1-1.061 0z\" style \/><\/g><\/svg><\/a><div class=\"link-text\" data-anchor=\"\u00bfPor qu\u00e9 es importante una estrategia de go-to-market?\" data-section=\"por-que-es-importante\">\n<h2>\u00bfPor qu\u00e9 es importante una estrategia de go-to-market?<\/h2>\n<\/div><\/div>\n<p>En un mundo ideal sin fricci\u00f3n no competitivo, lanzar\u00edas tu producto con un solo clic seguido de un \u00fanico tuit. Todo el mundo sabr\u00eda entonces que tu producto existe, lo querr\u00eda y las cosas funcionar\u00edan por s\u00ed solas. Pero, por desgracia, las cosas no son as\u00ed de f\u00e1ciles, as\u00ed que echemos un vistazo a las tres razones por las que necesitas una estrategia de&nbsp;GTM.<\/p>\n<h3>1. Prepararse para crecer<\/h3>\n<p>Prepararse para crecer quiere decir que puedes identificar el mejor escenario para el lanzamiento de tu producto y entender c\u00f3mo abordar esa oportunidad.<\/p>\n<p>Al desarrollar tu estrategia de go-to-market te aseguras de&nbsp;que:<\/p>\n<ul>\n<li>Tu producto resuelve un problema de tu audiencia objetivo.<\/li>\n<li>Existe demanda para tu producto y posiblemente m\u00e1s demanda en el futuro cercano.<\/li>\n<li>Tus clientes ver\u00e1n el valor de tu producto y ser\u00e1n capaces de pagarlo.<\/li>\n<li>Los beneficios de tu producto permitir\u00e1n que tu empresa crezca.<\/li>\n<li>No est\u00e1s entrando en un mercado sobresaturado.<\/li>\n<li>Tienes ventaja sustancial sobre la competencia.<\/li>\n<li>Est\u00e1s operativamente preparado para el crecimiento (o tienes un plan para escalar).<\/li>\n<\/ul>\n<h3>2. Decrecer el riesgo<\/h3>\n<p>Al contrario que al prepararse para el crecimiento, el papel de mitigador de riesgo de una estrategia de go-to-market es ayudarte a identificar el peor escenario posible y a hacer todo lo posible para evitarlo.<\/p>\n<p>\u00bfCu\u00e1l es el riesgo?<\/p>\n<p>Si el lanzamiento de tu producto fracasa, puede que sea dif\u00edcil para tu producto o marca recuperar terreno, ya que las malas reviews pueden lastrar al producto y a la marca que lo respalda. Aunque no es un gran problema para gigantes como Microsoft y Apple, que pueden permitirse un fiasco, la mayor parte de empresas no tienen presupuestos virtualmente ilimitados ni redes de seguridad.<\/p>\n<h3>3. Alinea la empresa hacia el lanzamiento de producto<\/h3>\n<p>Prepararse para un lanzamiento de producto a menudo se pierde en las operaciones prosaicas del d\u00eda a d\u00eda. Pero, \u00bfqu\u00e9 mejor momento para conseguir el acuerdo de todos los departamentos? \u00bfQu\u00e9 otra forma de gestionar las expectativas del lanzamiento?<\/p>\n<p>Alinear a la compa\u00f1\u00eda implica que todo el mundo sepa que est\u00e1s a punto de lanzar el producto y que est\u00e9n preparados cuando pulses el ese bot\u00f3n grande y rojo de \u201clanzar\u201d.<\/p>\n<p>As\u00ed que no m\u00e1s \u201cmarketing no nos dio ning\u00fan material\u201d, no m\u00e1s \u201cventas no tiene ni idea de lo que est\u00e1n vendiendo\u201d y no m\u00e1s representantes de atenci\u00f3n al cliente buscando respuestas por la empresa. Nadie necesita ese tipo de&nbsp;drama.<\/p>\n<h3>4. Eval\u00faa y asegura recursos<\/h3>\n<p>Antes incluso de contemplar el lanzamiento de cualquier cosa, necesitas asegurarte de que tienes tiempo suficiente para prepararte y dinero suficiente para apoyar tus t\u00e1cticas. Una estrategia de go-to-market asegura todo esto formalmente.<\/p>\n<div class=\"post-nav-link clearfix\" id=\"section1\"><a class=\"subhead-anchor\" data-tip=\"tooltip__copielink\" rel=\"#section1\"><svg width=\"19\" height=\"19\" viewBox=\"0 0 14 14\" style><g fill=\"none\" fill-rule=\"evenodd\"><path d=\"M0 0h14v14H0z\" \/><path d=\"M7.45 9.887l-1.62 1.621c-.92.92-2.418.92-3.338 0a2.364 2.364 0 0 1 0-3.339l1.62-1.62-1.273-1.272-1.62 1.62a4.161 4.161 0 1 0 5.885 5.884l1.62-1.62L7.45 9.886zM5.527 5.135L7.17 3.492c.92-.92 2.418-.92 3.339 0 .92.92.92 2.418 0 3.339L8.866 8.473l1.272 1.273 1.644-1.643A4.161 4.161 0 1 0 5.897 2.22L4.254 3.863l1.272 1.272zm-.66 3.998a.749.749 0 0 1 0-1.06l2.208-2.206a.749.749 0 1 1 1.06 1.06L5.928 9.133a.75.75 0 0 1-1.061 0z\" style \/><\/g><\/svg><\/a><div class=\"link-text\" data-anchor=\"C\u00f3mo crear una estrategia go-to-market\" data-section=\"como-crear-estrategia-go-to-market\">\n<h2>C\u00f3mo crear una estrategia go-to-market<\/h2>\n<\/div><\/div>\n<p>No puedes predecir todo. Nadie puede. Pero a\u00fan as\u00ed, hay muchas cosas que <em>puedes <\/em>predecir y que influyen a la hora de lanzar un producto. As\u00ed que en lugar de reinventar la rueda, vamos a recorrer los pasos para crear una estrategia de go-to-market bas\u00e1ndonos en componentes testados y probados, paso a&nbsp;paso.<\/p>\n<ol>\n<li>Identifica tu mercado (junto a tus competidores)<\/li>\n<li>Identifica a tu cliente<\/li>\n<li>Define el posicionamiento de producto y el precio<\/li>\n<li>Define los mensajes de producto y las t\u00e1cticas principales de marketing<\/li>\n<li>Define la distribuci\u00f3n del producto<\/li>\n<li>Sincroniza marketing, ventas y atenci\u00f3n al cliente<\/li>\n<li>Determina el presupuesto, marco temporal y recursos necesarios<\/li>\n<li>Define tus m\u00e9tricas de&nbsp;\u00e9xito<\/li>\n<\/ol>\n<h3>1. Identifica tu mercado (junto a tus competidores)<\/h3>\n<p>La investigaci\u00f3n de mercados es tu primera parada obligada. Cuanto antes puedas hacerlo, mejor. Sin embargo, ya que este es un proceso muy importante y que consume mucho tiempo, hemos escrito un <a href=\"https:\/\/ahrefs.com\/blog\/es\/investigacion-de-mercados\/\">art\u00edculo separado sobre este tema<\/a>.<\/p>\n<p>Perm\u00edteme ofrecer unas pocas pinceladas de ese art\u00edculo para que podamos seguir adelante.<\/p>\n<p><strong>Primero<\/strong>, el 90% de tu \u00e9xito radica en tener los datos adecuados. Necesitas recoger y analizar investigaci\u00f3n de fuentes primarias (realizada por ti) y secundarias (hecha por otros y ya disponible). La investigaci\u00f3n secundaria incluye informes sectoriales, estad\u00edsticas de la industria, whitepapers, etc. y es la forma m\u00e1s asequible y r\u00e1pida (relativamente) de conseguir datos sobre tu mercado.<\/p>\n<p>Por ejemplo, si est\u00e1s en el negocio de la impresi\u00f3n 3D necesitas conseguir los Wohlers Report, que ofrecen un \u201can\u00e1lisis y revisi\u00f3n global de la fabricaci\u00f3n por adici\u00f3n (AM, <em>additive manufacturing<\/em>) e impresi\u00f3n 3D\u201d<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/Untitled-26.png\"><a href=\"https:\/\/wohlersassociates.com\/\" target=\"_blank\" rel=\"noopener\">Wohler\u2019s Report<\/a>\u2014 un ejemplo de investigaci\u00f3n de mercados secundaria para la industria de la impresi\u00f3n 3D. Fuente: https:\/\/wohlersassociates.com\/<\/p>\n<p>Informes como este ofrecen una perspectiva general del mercado y una visi\u00f3n a vista de p\u00e1jaro de lo que te&nbsp;rodea.<\/p>\n<p><strong>Segundo<\/strong>, ninguna investigaci\u00f3n de mercado est\u00e1 completa sin an\u00e1lisis competitivo. De verdad, es necesario. Un an\u00e1lisis competitivo te dice lo que la competencia est\u00e1 haciendo bien, mal y lo que no est\u00e1 haciendo. Aqu\u00ed va una gu\u00eda paso a paso sobre <a href=\"https:\/\/ahrefs.com\/blog\/es\/analisis-competitivo\/\">c\u00f3mo hacerlo<\/a>.<\/p>\n<p>Para cuando acabes tu an\u00e1lisis competitivo deber\u00edas ser capaz de realizar un an\u00e1lisis FODA o DAFO (SWOT, por sus siglas en ingl\u00e9s).<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/Untitled-3.jpg\"><\/p>\n<p>Adem\u00e1s de los tipos y m\u00e9todos de investigaci\u00f3n de mercados mencionados arriba, te animo a realizar investigaci\u00f3n primaria. Realizar investigaci\u00f3n primaria puede revelar conocimientos \u00fanicos sobre el mercado y ayudarte a entender d\u00f3nde reside el potencial sin explotar del mercado. Para esto, considera encuestas, entrevistas y focus groups.<\/p>\n<p>Para relacionar los hallazgos clave de la investigaci\u00f3n de mercado, considera la siguiente tabla. La hemos rellenado con datos de muestra para la industria de impresi\u00f3n 3D. Si puedes rellenarla en base a tu investigaci\u00f3n, est\u00e1s preparado para el pr\u00f3ximo paso del proceso GTM.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/Untitled-30-1.jpg\"><\/p>\n<h3>2. Identifica a tu cliente<\/h3>\n<p>Una vez que tienes una idea del mercado, es hora de moverse un \u201cnivel m\u00e1s abajo\u201d y entender a qui\u00e9n vas a intentar venderle.<\/p>\n<p>Dependiendo de tus recursos, hay dos formas en las que puedes identificar a tus clientes:<\/p>\n<ul>\n<li><strong>La forma cient\u00edfica. <\/strong>Habla con clientes potenciales (en base a la investigaci\u00f3n de mercados que ya has realizado). Podr\u00edan ser tus leads, seguidores en redes sociales o simplemente personas que sepas que podr\u00edan estar interesadas en tu producto. Tambi\u00e9n puedes considerar el uso de servicios como <a href=\"https:\/\/www.surveymonkey.com\/market-research\/\" target=\"_blank\" rel=\"noopener\">SurveyMonkey<\/a>, <a href=\"https:\/\/www.usertesting.com\/homepage_c\" target=\"_blank\" rel=\"noopener\">UserTesting<\/a>, o <a href=\"https:\/\/remesh.ai\/\" target=\"_blank\" rel=\"noopener\">Remesh<\/a> para llegar a estas personas.<\/li>\n<li><strong>La forma de la <\/strong><strong>suposici\u00f3n bien<\/strong><strong> fundada. <\/strong>Si no puedes hablar con personas reales en esta fase, necesitas ponerte creativo. Por ejemplo, puede que tu competidor publique un estudio con una cita de un cliente al que puedas investigar en LinkedIn. Tambi\u00e9n puedes mirar datos de la industria del tipo de puesto que tiene la persona en la empresa. Puedes descubrir, por ejemplo, que la b\u00fasqueda org\u00e1nica es la prioridad de gasto #1, seg\u00fan una encuesta para CMOs (directores de marketing).<\/li>\n<\/ul>\n<p>Normalmente, el producto final de este paso es un <em>buyer persona<\/em>\u2014una persona imaginaria que creas que representa las caracter\u00edsticas comunes de tus clientes (un arquetipo). Ten en cuenta que tu mercado objetivo puede tener varios buyer personas.<\/p>\n<p>Aqu\u00ed va un ejemplo del aspecto que puede tener un buyer persona para Ahrefs:<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/Untitled-30.png\"><\/p>\n<p><em>Ana Agencia<\/em><\/p>\n<p><em>Propietaria de Agencia SEO<\/em><\/p>\n<p><em>Ana es la fundadora de una agencia SEO que trabaja para negocios de tama\u00f1o peque\u00f1o y mediano en Espa\u00f1a<\/em><em>.<\/em><\/p>\n<p><em>** Sus mayores retos<\/em><\/p>\n<p><em>Formar a empleados, informes de clientes, escalar el&nbsp;SEO.<\/em><\/p>\n<p><em>** Sus objetivos<\/em><\/p>\n<p><em>Conseguir m\u00e1s clientes, mejorar la eficiencia, aprender y probar nuevas t\u00e1cticas SEO.<\/em><\/p>\n<p><em>** \u00bfCu\u00e1l es nuestra propuesta de&nbsp;valor?<\/em><\/p>\n<p><em>Ahrefs ayuda a profesionales SEO a escalar su negocio y mejorar sus habilidades ofreciendo una plataforma todo en uno, formaci\u00f3n gratuita y una comunidad y soporte apasionados.<\/em><\/p>\n<p><em>** \u00bfQu\u00e9 tipo de contenido le interesar\u00e1 a&nbsp;ella?<\/em><\/p>\n<p><em>Tutoriales directos de SEO y casos de estudio que sus empleados puedan seguir y de los que aprender.<\/em><\/p>\n<p><em> - Edad: 33&nbsp;a\u00f1os.<\/em><\/p>\n<p><em> - Ubicaci\u00f3n: Espa\u00f1a.<\/em><\/p>\n<p><em> - T\u00edtulo: CEO.<\/em><\/p>\n<p><em> - Tama\u00f1o de la organizaci\u00f3n.: 20-50<\/em><\/p>\n<p><em>\u00bfD\u00f3nde consume contenido?<\/em><\/p>\n<p><em>El blog de Ahrefs, Backlinko, SEJ.<\/em><\/p>\n<p><em>\u00bfQu\u00e9 redes sociales usa?<\/em><\/p>\n<p><em>Facebook<\/em><\/p>\n<p><em>Twitter<\/em><\/p>\n<p><em>LinkedIn<\/em><\/p>\n<p>Un buyer persona te ayuda a visualizar el viaje de tu cliente, internalizar qui\u00e9nes son y empatizar con sus retos y objetivos.<\/p>\n<p>Puedes usar el buyer persona como una ayuda para organizar y comunicar aprendizajes sobre tus clientes potenciales. Si est\u00e1s buscando m\u00e1s informaci\u00f3n sobre este tema, aqu\u00ed va una gu\u00eda detallada para crear un <a href=\"https:\/\/cxl.com\/blog\/user-personas\/\" target=\"_blank\" rel=\"noopener\">buyer persona<\/a>.<\/p>\n<p>Si vendes B2B, tambi\u00e9n merece la pena mapear el proceso de decisi\u00f3n dentro del tipo de organizaci\u00f3n al que te diriges. Esto se conoce como centro de compras y te ayuda a determinar hacia qui\u00e9n dirigir el marketing de tu producto o servicio.<\/p>\n<ul>\n<li><strong>Iniciador:<\/strong> comienza el proceso de compra<\/li>\n<li><strong>Usuario:<\/strong> el usuario final real del producto<\/li>\n<li><strong>Influencer:<\/strong> convence a otros sobre el producto<\/li>\n<li><strong>Decisor:<\/strong> aprueba la compra<\/li>\n<li><strong>Comprador: <\/strong>due\u00f1o del presupuesto<\/li>\n<li><strong>Aprobador:<\/strong> supervisores que empujan la iniciativa a una escala mayor<\/li>\n<li><strong>Guardi\u00e1n:<\/strong> controla el flujo de informaci\u00f3n<\/li>\n<\/ul>\n<p>Por ejemplo, pongamos que te est\u00e1s dirigiendo a agencias SEO. El centro de compras deber\u00eda ser algo&nbsp;as\u00ed:<\/p>\n<ul>\n<li><strong>Iniciador:<\/strong> responsable de SEO senior<\/li>\n<li><strong>Usuario:<\/strong> responsables SEO, responsables de contenido, analistas SEO<\/li>\n<li><strong>Influencer:<\/strong> director de marketing de contenidos<\/li>\n<li><strong>Decisor:<\/strong> Director de&nbsp;SEO<\/li>\n<li><strong>Comprador: <\/strong>especialista de operaciones<\/li>\n<li><strong>Aprobador:<\/strong> CEO<\/li>\n<li><strong>Guardi\u00e1n:<\/strong> especialista de operaciones<\/li>\n<\/ul>\n<h3>3. Define el posicionamiento de producto y precio<\/h3>\n<p>El posicionamiento de producto y el precio forman las bases de c\u00f3mo el mercado percibir\u00e1 tu producto. Si se desarrollan correctamente, funcionan en conjunto para ayudar a la adopci\u00f3n de tu producto.<\/p>\n<h4>Posicionamiento de producto<\/h4>\n<p>El posicionamiento es uno de esos conceptos cl\u00e1sicos atemporales en marketing. Fue acu\u00f1ado a finales de los a\u00f1os 60 por Jack Trout y m\u00e1s tarde se analiz\u00f3 en el bestseller escrito junto a Al Ries: \u201cPosicionamiento: la batalla por su&nbsp;mente\u201d.<\/p>\n<p>Seg\u00fan Trout y Ries, posicionar un producto (o marca) es asegurarse de que los clientes identificar\u00e1n de forma instant\u00e1nea ese producto con un beneficio concreto o un peque\u00f1o conjunto de beneficios.<\/p>\n<p>\u00bfPor qu\u00e9 solo un beneficio o un peque\u00f1o conjunto de beneficios? Porque en nuestra sociedad cada vez m\u00e1s ruidosa, los productos y marcas necesitan mensajes sobre simplificados para destacar.<\/p>\n<p>Vamos a ver un ejemplo de posicionamiento. Este ejemplo es probablemente uno de los m\u00e1s espectaculares y famosos\u2014del servicio de alquiler de coches Avis:<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/Untitled-4.jpg\"><em>Avis es tan solo el N\u00ba&nbsp;2.&nbsp;<\/em><\/p>\n<p><em>en el alquiler de coches.<\/em><\/p>\n<p><em>As\u00ed que, \u00bfpor qu\u00e9 elegirnos?<\/em><\/p>\n<p><em>Nos esforzamos m\u00e1s.<\/em><\/p>\n<p><em>(Cuando no eres el m\u00e1s grande, tienes que hacerlo).<\/em><\/p>\n<p><em>Simplemente no nos podemos permitir ceniceros sucios. O dep\u00f3sitos medio vac\u00edos. O limpiaparabrisas estropeados. O coches sin lavar. O ruedas bajas. O algo inferior a ajustes del asiento que se ajusten. <\/em><em>Calefacci\u00f3n que caliente<\/em><em>. Descongelante que descongele.<\/em><\/p>\n<p><em>Obviamente, en lo que m\u00e1s nos esforzamos es en ser amables. Para que empieces directamente con un coche nuevo, como un Ford super-torque y una amable sonrisa. Para saber, pongamos, d\u00f3nde conseguir un buen sandwich de pastrami en Duluth.<\/em><\/p>\n<p><em>\u00bfPor qu\u00e9?<\/em><\/p>\n<p><em>Porque no podemos permitirnos darte por&nbsp;hecho.&nbsp;<\/em><\/p>\n<p><em>Ven con nosotros la pr\u00f3xima vez.<\/em><\/p>\n<p><em>La <\/em><em>l\u00ednea<\/em><em>en nuestro mostrador es m\u00e1s&nbsp;corta.<\/em><\/p>\n<p>Fuente: <a href=\"https:\/\/www.businessinsider.com\/heres-the-new-tagline-avis-will-use-after-50-years-of-we-try-harder-2012-8?IR=T\" target=\"_blank\" rel=\"noopener\">Businessinsider.com<\/a><\/p>\n<p>En el momento de publicaci\u00f3n de este anuncio Avis era el #2 en el negocio de alquiler de coches. Avis tom\u00f3 ese hecho inoportuno y le dio la vuelta al&nbsp;guion.<\/p>\n<p>Slack es otro buen ejemplo de posicionamiento de producto\u2026<\/p>\n<p>Desde el principio Slack posicion\u00f3 su producto como la herramienta anti-email y empuj\u00f3 esta narrativa en cada oportunidad de marketing.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/Untitled-5.jpg\"><\/p>\n<p><em>Lo que se siente al recibir un 48% menos de emails.<\/em><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/Untitled-6.jpg\"><\/p>\n<p><em>Dev lanz\u00f3 una campa\u00f1a sin enviar un solo&nbsp;email.<\/em><\/p>\n<p><em><strong>Esa es la colaboraci\u00f3n en&nbsp;Slack.<\/strong><\/em><\/p>\n<p>Eso es en resumen el posicionamiento. No es crear algo nuevo o diferente; es manipular lo que ya est\u00e1 en la mente de los prospectos.<\/p>\n<p>La herramienta m\u00e1s \u00fatil a la hora de desarrollar tu posicionamiento es el mapa de percepciones (tambi\u00e9n llamado mapa de posicionamiento). Un mapa de percepciones ilustra el posicionamiento de productos (o marcas) en la mente de los consumidores.<\/p>\n<p>Para crear uno, identifica atributos (tambi\u00e9n conocidos como dimensiones) que definan el espacio del producto y determinen la posici\u00f3n de productos dados en ese espacio.<\/p>\n<p>La mejor forma (m\u00e1s cient\u00edfica) de desarrollar un mapa de percepci\u00f3n es evaluar los factores que impacten en las decisiones de compra de los clientes y pedir a una muestra de tus prospectos que eval\u00faen productos en esos factores. Normalmente puedes dibujar los resultados en un gr\u00e1fico de dos dimensiones.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/Untitled-7.jpg\"><\/p>\n<p><em>Juvenil - Maduro<\/em><\/p>\n<p><em>Tradicional - Ex\u00f3tico<\/em><\/p>\n<p>Nestl\u00e9 encarg\u00f3 el mapa de percepci\u00f3n de arriba para ayudar a traer al mercado una nueva chocolatina (<a href=\"https:\/\/www.edenkleiman.com\/switch-bar\" target=\"_blank\" rel=\"noopener\">caso de estudio<\/a>). Muestra c\u00f3mo los clientes perciben a los chocolates competidores en Nueva Zelanda. Por ejemplo, consideran el chocolate negro con chili de Lindt como una elecci\u00f3n madura y ex\u00f3tica y Milkybar como una opci\u00f3n m\u00e1s tradicional, atractiva para una audiencia m\u00e1s&nbsp;joven.<\/p>\n<p>A la hora de posicionar un producto, aseg\u00farate de que cumples estos requisitos:<\/p>\n<ul>\n<li><strong>El cliente objetivo se preocupa por tu posicionamiento. <\/strong>Puede ser algo \u00fanico, pero completamente irrelevante. Eso no funcionar\u00e1.<\/li>\n<li><strong>La organizaci\u00f3n tiene caracter\u00edsticas \u00fanicas para hacerlo. <\/strong>\u00bfEn que se basar\u00e1 el posicionamiento? \u00bfCu\u00e1l es tu ventaja competitiva? \u00bfPor qu\u00e9 deber\u00eda el cliente creerte? \u00bfTiene el producto las funcionalidades adecuadas?<\/li>\n<li><strong>Los competidores no pueden hacerlo adecuadamente. <\/strong>Pero t\u00fa&nbsp;s\u00ed.<\/li>\n<\/ul>\n<h4>Precio<\/h4>\n<p>El precio de tu producto deber\u00eda ser una funci\u00f3n de tu posicionamiento. Si quieres que los clientes vean tu producto como una elecci\u00f3n asequible, tu precio deber\u00eda comunicar eso.<\/p>\n<p>Vale, un producto nuevo por encima de todo debe dar beneficios (a no ser que est\u00e9s haciendo alguna jugada arriesgada como una guerra de precios para desangrar a la competencia). Si quieres aprender m\u00e1s sobre asegurar los beneficios con el precio del producto, lee <a href=\"https:\/\/sumo.com\/stories\/how-to-price-a-product\" target=\"_blank\" rel=\"noopener\">este art\u00edculo<\/a>. De momento, vamos a mantener el foco en lo relativo al marketing.<\/p>\n<p>Un ejercicio \u00fatil para ayudarte a determinar el precio de un producto es ubicar d\u00f3nde se encuentra en t\u00e9rminos de precio vs. beneficios (ver la tabla de abajo). Mientras est\u00e1s en ello, tambi\u00e9n puedes mapear a tus competidores. En general, las estrategias ganadoras son las que est\u00e1n en&nbsp;verde.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/Untitled-37.png\"><\/p>\n<h3>4. Define los mensajes de producto y las t\u00e1cticas principales de marketing<\/h3>\n<p>Ahora es el momento de discutir qu\u00e9 decirle a los clientes potenciales y qu\u00e9 t\u00e1cticas y canales deber\u00edas usar para comunicarte con&nbsp;ellos.<\/p>\n<h4>Mensajes de producto<\/h4>\n<p>Los mensajes de producto atrapan la atenci\u00f3n de tu audiencia objetivo y la educan sobre tu producto.<\/p>\n<p>Desde un punto de vista operativo, los mensajes de producto son el centro estrat\u00e9gico de tu comunicaci\u00f3n con el cliente. Es la matriz de cada mensaje que ser\u00e1 elaborado para tu audiencia objetivo, ya sea un simple anuncio digital, una nota de prensa, formaci\u00f3n de producto o el contenido de la p\u00e1gina web del producto.<\/p>\n<p>Debajo encontrar\u00e1s un ejemplo de un marco de trabajo de mensajes de producto rellenado con datos de nuestro producto. Si\u00e9ntete libre de usarlo, y, si te hace falta, multipl\u00edcalo por el n\u00famero de tus buyer persona.<\/p>\n<p>Para maximizar la efectividad del documento, deber\u00edas hacer que los departamentos de ventas, producto y posiblemente legal lo revisen.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/Untitled-39.jpg\"><\/p>\n<div class=\"recommendation\"><div class=\"recommendation-title\">PRO TIP<\/div><div class=\"recommendation-content\">\n<p>Al hacer esto, enf\u00f3cate en lo que te haga \u00fanico, mant\u00e9n las cosas breves y directas y no intentes agradar a todo el&nbsp;mundo.<\/p>\n<\/div><\/div>\n<h4>Principales t\u00e1cticas de marketing<\/h4>\n<p>\u201cSi lo creas, vendr\u00e1n\u201d.<\/p>\n<p>No cuentes con&nbsp;ello.<\/p>\n<p>Los mercados est\u00e1n saturados con soluciones para casi cualquier cosa y los clientes est\u00e1n sobrecargados con informaci\u00f3n. Necesitas superar el ruido\u2014y ah\u00ed es d\u00f3nde entran las t\u00e1cticas de marketing.<\/p>\n<p>Las t\u00e1cticas de marketing son actividades que te ayudan a alcanzar objetivos de marketing. Son medios para un&nbsp;fin.<\/p>\n<p>En mi opini\u00f3n, hay dos caminos que puedes tomar al desarrollar tus t\u00e1cticas de marketing:<\/p>\n<ol>\n<li><strong>Copiar a otros. <\/strong>Descubre c\u00f3mo empresas parecidas introdujeron sus productos o insp\u00edrate a partir de empresas\/marketeros que admiras. Mira qu\u00e9 resultados consiguieron y qu\u00e9 tuvieron que invertir para conseguirlo. Despu\u00e9s remezcla, mejora y \u00fasalo para ti&nbsp;mismo.<\/li>\n<li><strong>Ponte creativo<\/strong> y desarrolla algo personalizado y&nbsp;\u00fanico.<\/li>\n<\/ol>\n<p>Vamos a discutir la primera aproximaci\u00f3n: <strong>copiar a&nbsp;otros.&nbsp;<\/strong><\/p>\n<p>En primer lugar, no hay nada de qu\u00e9 avergonzarse por copiar a otros. Toma el marketing de contenidos como ejemplo. \u00bfQui\u00e9n lo empez\u00f3? \u00bfMichelin? \u00bfJohn Deere? Nadie lo sabe y a nadie le importa.<\/p>\n<p>Lo que le importa a la gente es si funciona.<\/p>\n<p>Hoy, miles de empresas usan el marketing de contenidos, inclu\u00eddos nosotros. Este hilo de Twitter explica la aproximaci\u00f3n de Ahrefs al marketing de contenidos:<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Let\u2019s talk about the \u201cROI of Content Marketing.\u201d<\/p>\n<p>Far too often us marketers get challenged with this question by our boss (or our client):<\/p>\n<p>- How do I know that my investment in content will guarantee a positive return? \u2026&amp; how can I *MEASURE* it?<\/p>\n[Read more..]\n<p>\u2014 Tim Soulo (@timsoulo) <a href=\"https:\/\/twitter.com\/timsoulo\/status\/1374242996531597315?ref_src=twsrc%5Etfw\">March 23,&nbsp;2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><em>Vamos a hablar del \u201cROI del Marketing de Contenidos\u201d.<\/em><\/p>\n<p><em>Demasiado a menudo nuestro jefe (o cliente) nos desaf\u00eda a los marketeros con esta pregunta:<\/em><\/p>\n<ul>\n<li><em>\u00bfC\u00f3mo s\u00e9 que mi inversi\u00f3n en contenido tendr\u00e1 un retorno positivo? \u2026 &amp; y c\u00f3mo puedo *MEDIRLO*?<\/em><\/li>\n<\/ul>\n<p>Pero copiar es un arte en s\u00ed mismo. Todos hemos o\u00eddo la frase \u201clos buenos artistas copian, los grandes roban\u201d. En otras palabras, no intentes ser otra persona pero toma elementos de forma selectiva a partir de tus inspiraciones y \u00fasalos en beneficio propio.<\/p>\n<p>Puedes copiar (\u201crobar\u201d):<\/p>\n<ul>\n<li>Canales de promoci\u00f3n<\/li>\n<li>Bater\u00eda tecnol\u00f3gica de marketing (marketing tech&nbsp;stack)<\/li>\n<li>Formatos de anuncios<\/li>\n<li><a href=\"https:\/\/ahrefs.com\/blog\/es\/tipos-de-marketing\/\" target=\"_blank\" rel=\"noopener\">Tipos de marketing<\/a> colateral<\/li>\n<li>Tipos de contenido<\/li>\n<li>Dise\u00f1o gr\u00e1fico de la web (pero no de tus competidores directos)<\/li>\n<li>T\u00e1cticas SEO<\/li>\n<\/ul>\n<p>Probablemente no deber\u00edas copiar:<\/p>\n<ul>\n<li>Redacci\u00f3n creativa \/ copywriting (titulares, copy de anuncios, straplines, etc.)<\/li>\n<li>Logos y otros elementos de la identidad corporativa<\/li>\n<li>Propuestas de&nbsp;valor<\/li>\n<\/ul>\n<p>Ahora, vamos a hablar del segundo camino: <strong>ponerse creativo<\/strong>.<\/p>\n<p>Ponerse creativo quiere decir mirar las cosas desde una perspectiva distinta y pensar fuera de la&nbsp;caja.<\/p>\n<p>Hemos cubierto unas pocas t\u00e1cticas creativas de marketing <a href=\"https:\/\/ahrefs.com\/blog\/es\/ideas-marketing\/\">aqu\u00ed<\/a> y <a href=\"https:\/\/ahrefs.com\/blog\/creative-marketing\/\" data-ahr=\"https:\/\/ahrefs.com\/blog\/es\/creative-marketing\/\">aqu\u00ed<\/a>.<\/p>\n<p>Si quieres llegar a t\u00e1cticas propias, intenta adoptar una nueva perspectiva.<\/p>\n<p>Para hacer eso, necesitas establecer tus objetivos\u2014los n\u00fameros en bruto est\u00e1n bien en este punto\u2014y trabajar hacia atr\u00e1s para imaginarte c\u00f3mo alcanzarlos.<\/p>\n<p>Por ejemplo, pongamos que tu meta es convertir 2.000 clientes en dos a\u00f1os despu\u00e9s del lanzamiento de tu producto. Antes de que esto pase, \u00bfqu\u00e9 requisitos se tienen que cumplir? \u00bfC\u00f3mo se desarrolla esa historia de conseguir 2.000 clientes? O, en otras palabras:<\/p>\n<ul>\n<li>\u00bfQu\u00e9 aprendieron esos clientes y experimentaron sobre el producto que les hizo comprar?<\/li>\n<li>\u00bfD\u00f3nde aprendieron sobre \u00e9l y lo experimentaron?<\/li>\n<li>\u00bfDe d\u00f3nde vinieron los clientes y qu\u00e9 fue lo primero que aprendieron?<\/li>\n<li>\u00bfCu\u00e1ntas personas necesitas que pasen por la puerta para convertir a 2.000?<\/li>\n<\/ul>\n<div class=\"further-reading\"><div class=\"reading-title\">Lecturas complementarias<\/div><div class=\"reading-content\">\n<ul>\n<li><a href=\"https:\/\/ahrefs.com\/blog\/es\/tacticas-marketing\/\">16 T\u00e1cticas de Marketing Que Funcionan en&nbsp;2021<\/a><\/li>\n<li><a href=\"https:\/\/ahrefs.com\/blog\/es\/tacticas-generacion-leads\/\">10 T\u00e1cticas de Generaci\u00f3n de Leads Que Funcionan (Con Ejemplos)<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n<h3>5. Define la distribuci\u00f3n del producto<\/h3>\n<p>La distribuci\u00f3n es el proceso de hacer que un producto o servicio est\u00e9 disponible para el cliente.<\/p>\n<p>Por simplicidad, podemos segmentar los canales de distribuci\u00f3n en base al tipo de producto: digital o f\u00edsico.<\/p>\n<h4>Productos digitales<\/h4>\n<ul>\n<li><strong>Propietaria\/directa<\/strong><strong>. <\/strong>Solo puedes comprar software a trav\u00e9s de tu sitio web. Controlas la experiencia por completo y no necesitas pagar a una tercera parte (excepto al que procesa el pago). Este es probablemente el modelo m\u00e1s&nbsp;com\u00fan.<\/li>\n<li><strong>Tienda de apps y marketplaces.<\/strong> Tu software solo est\u00e1 disponible (o principalmente) a trav\u00e9s de servicios de terceros como la App Store de Apple o la plataforma con la que te integres, como el Atlassian Marketplace. Las tasas var\u00edan entre plataformas, desde el 5% durante el primer a\u00f1o, hasta el 30% de tus ingresos despu\u00e9s.<\/li>\n<li><strong>Programas de partners<\/strong>. Pagas una comisi\u00f3n (u ofreces otros beneficios) a aliados que promocionen tu negocio (<a href=\"https:\/\/ahrefs.com\/blog\/es\/marketing-de-afiliados\/\">marketing de afiliados<\/a>) o act\u00faas como partner de servicio (Xero <a href=\"https:\/\/sixteenventures.com\/saas-channels#:~:text=Look%20at%20a%20company%20like%20Xero%2C%20with%20their%20SaaS%20accounting%20package%2C%20and%20how%20~50%25%20of%20their%20business%20is%20via%20channels%3B%20specifically%20CPA%20and%20Accounting%20firms.\" target=\"_blank\" rel=\"noopener\">supuestamente consigue el ~50%<\/a> de su negocio a trav\u00e9s de su programa de partners). Este es normalmente un modelo auxiliar.<\/li>\n<li><strong>OEM<\/strong>. Tu producto est\u00e1 empaquetado dentro de otro producto final. Por ejemplo, en Amazon AWS se ejecutan muchos servicios populares, como Netflix.<\/li>\n<\/ul>\n<h4>Productos f\u00edsicos<\/h4>\n<ul>\n<li><strong>Distribuci\u00f3n directa<\/strong><strong>.<\/strong> Vendes directamente a clientes, ya sea en tiendas online o f\u00edsicas. Mantienes todos los ingresos y tienes contacto directo con tus clientes. Al contrario que en los productos digitales, los fabricantes de hardware rara vez conf\u00edan en este como su \u00fanico canal. Normalmente emplean una mezcla de canales de distribuci\u00f3n.<\/li>\n<li><strong>Distribuci\u00f3n en masa (intensiva)<\/strong>. Ofreces tus productos en tantos sitios como sea posible. Puedes esperar que un distribuidor se quede hasta un 40% de tus ingresos.<\/li>\n<li><strong>Distribuci\u00f3n selectiva<\/strong>. Tu producto se vende solo en tiendas elegidas\u2014normalmente aquellas especializadas en tu nicho que pueden ofrecer valor a\u00f1adido, como atenci\u00f3n al cliente de alta calidad.<\/li>\n<li><strong>Distribuci\u00f3n exclusiva. <\/strong>Firmas un acuerdo con uno o dos partners que tienen los derechos exclusivos para ofrecer tu producto en una regi\u00f3n concreta (eso normalmente implica excluir tambi\u00e9n las ventas directas en esa regi\u00f3n).<\/li>\n<li><strong>OEM. <\/strong>Tu producto est\u00e1 empaquetado dentro de otro producto final. Piensa en \u201cIntel inside\u201d y Microsoft Windows entregado con la mayor\u00eda de los&nbsp;PCs.<\/li>\n<\/ul>\n<p>As\u00ed que, como puedes ver, la arquitectura de tu producto define bastante tu distribuci\u00f3n. Por ejemplo, las apps hechas para plataformas espec\u00edficas tienen solo una forma de distribuci\u00f3n y la elecci\u00f3n habitual para los productos SaaS es la distribuci\u00f3n directa.<\/p>\n<p>Otro factor que puede determinar tu distribuci\u00f3n es el entorno de mercado, por ejemplo, los h\u00e1bitos del consumidor y tu competencia. Si todo el mundo en el mercado se apoya en alg\u00fan tipo de modelo de distribuci\u00f3n de terceras partes ser\u00e1 dif\u00edcil penetrar el mercado confiando solo en las ventas directas. Y s\u00ed, eso aplica incluso a&nbsp;Apple:<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/Untitled-8.jpg\"><\/p>\n<p><em>Gr\u00e1fico 1: Porcentaje de las ventas en Estados Unidos por producto y minorista (12 meses, finales de septiembre de&nbsp;2017)<\/em><\/p>\n<p><em>Apple<\/em><\/p>\n<p><em>Best Buy<\/em><\/p>\n<p><em>operador<\/em><\/p>\n<p>Dicho esto, la mayor parte de las veces tendr\u00e1s algo de espacio para mezclar y combinar. Como en el caso de Xero, puede tener sentido ofrecer el producto directamente a la vez que a trav\u00e9s de intermediarios. O puedes mezclar distribuci\u00f3n directa con masiva y OEM, como hace Intel con sus procesadores.<\/p>\n<p>En cualquier caso, considera los costes y beneficios de elegir un modelo sobre el resto. Cualquier tipo de distribuci\u00f3n indirecta cortar\u00e1 una parte de tus ingresos, pero puede incrementar tus ingresos en el largo plazo poniendo tu producto frente a m\u00e1s&nbsp;gente.<\/p>\n<h3>6. Sincroniza marketing, ventas y atenci\u00f3n al cliente<\/h3>\n<p>A medida que nos acercamos al final del proceso de crear una estrategia de go-to-market te dar\u00e1s cuenta de que quiz\u00e1 la parte m\u00e1s complicada queda atr\u00e1s. A partir de ahora todo depende m\u00e1s de factores internos que externos.<\/p>\n<p>Primero, necesitas coordinar todo sincronizando a los departamentos de marketing, ventas y atenci\u00f3n al cliente para el lanzamiento de producto.<\/p>\n<p>Como todas las organizaciones son distintas, no te dar\u00e9 consejos sobre c\u00f3mo hacer \u201cclic\u201den tu organizaci\u00f3n. En su lugar, me gustar\u00eda compartir unos pocos consejos sobre qu\u00e9 me funcion\u00f3 cuando lanc\u00e9 nuevos productos o funcionalidades clave:<\/p>\n<ol>\n<li><strong>Trabaja tanto como sea posible con otros departamentos<\/strong>. Esto es algo obligado cuando desarrollas tu estrategia GTM (en cualquier fase del proceso). Realiza entrevistas internas (pero no las hagas formales) y pregunta a la gente por su visi\u00f3n e&nbsp;ideas.<\/li>\n<li><strong>Re\u00fane requisitos de otros departamentos. <\/strong>Pregunta a tus compa\u00f1eros de equipo que necesitan para apoyar el lanzamiento por su&nbsp;lado.<\/li>\n<li><strong>Crea \u201cla fuente de la verdad\u201d. <\/strong>Esta es documentaci\u00f3n fundamental que sirve como la fuente a la que acudir para cualquier trabajo futuro con el producto. Algunos ejemplos incluyen notas de prensa, manuales de producto (o bases de conocimiento online), tablas de precios, gu\u00edas de mensajes de venta y FAQs (preguntas frecuentes).<\/li>\n<\/ol>\n<h3>7. Determina el presupuesto, marco temporal y recursos necesarios<\/h3>\n<p>Llevar cualquier producto al mercado supondr\u00e1 tiempo, recursos y dinero. Necesitas definir estas cosas por adelantado si quieres llevar tu producto al mercado r\u00e1pidamente sin romper el banco o planificar cosas para las que no tienes recursos.<\/p>\n<p>Este tipo de tarea se aborda mejor con otros departamentos y directivos.<\/p>\n<p>Si est\u00e1s trabajando con un presupuesto fijo, destinar tiempo y recursos es relativamente directo. Simplemente divide el presupuesto entre t\u00e1cticas de marketing y divide tus t\u00e1cticas entre los miembros del equipo para asegurarte de que todo se hace a tiempo.<\/p>\n<p>Si tienes m\u00e1s flexibilidad en estas tres \u00e1reas, necesitar\u00e1s hacer algunas estimaciones para hacer despegar el proyecto. Aqu\u00ed van algunas opciones:<\/p>\n<ul>\n<li><strong>Usa datos de proyectos parecidos. <\/strong>Por ejemplo, el presupuesto de una estrategia GTM anterior.<\/li>\n<li><strong>Usa variables conocidas.<\/strong> Por ejemplo, puedes tomar tu CAC y multiplicarlo por el n\u00famero de clientes que esperas atraer el primer a\u00f1o.<\/li>\n<li><strong>Lista todo y s\u00famalo<\/strong>. Tan f\u00e1cil como suena. El truco aqu\u00ed es ser tan espec\u00edfico como sea posible a la hora de listar elementos del presupuesto, tiempo y recursos. Afortunadamente, hay herramientas para eso: plantillas gratuitas para Google Sheets o Excel, plantillas preparadas dentro de herramientas de gesti\u00f3n de proyecto (como Monday.com) y calculadoras online como Eastimate o Simplestimate.<\/li>\n<li><strong>Calcula la media para darte algo de margen. <\/strong>Se llama estimaci\u00f3n en tres puntos. Tomas tres estimaciones distintas y calculas la media. Tus tres estimaciones pueden ser: un escenario optimista, un escenario conservador y un escenario pesimista. Tu escenario conservador puede calcularse por uno de los m\u00e9todos listados arriba. Los otros escenarios ser\u00e1n versiones convenientemente modificadas del conservador.<\/li>\n<\/ul>\n<h3>8. Define tus m\u00e9tricas de&nbsp;\u00e9xito<\/h3>\n<p>Tus m\u00e9tricas de \u00e9xito enlazan tu objetivo y las medidas que la compa\u00f1\u00eda puede controlar para conseguir ese objetivo. Estas son en esencia dos filosof\u00edas que considerar al definir tus m\u00e9tricas de estrategia go-to-market.<\/p>\n<p><strong>La primera filosof\u00eda <\/strong>es medir las m\u00e9tricas clave del customer journey completo para el m\u00e1ximo conocimiento y control.<\/p>\n<p>Por ejemplo, podr\u00edas basar tus m\u00e9tricas de \u00e9xito en el modelo del volante. En este modelo, mides las tres fases principales del customer journey: atraer, interactuar y deleitar. El crecimiento ocurre como un producto \u201cderivado\u201d de optimizar para estas tres m\u00e9tricas. As\u00ed es c\u00f3mo HubSpot hace crecer su empresa (despu\u00e9s de deshacerse del antiguo modelo de embudo) y c\u00f3mo Jeff Bezos dise\u00f1\u00f3 la estrategia de crecimiento para Amazon.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/pasted-image-0-4.png\"><\/p>\n<p><strong>La segunda filosof\u00eda <\/strong>es hacer seguimiento de solo una o unas pocas m\u00e9tricas \u201cnorte verdadero\u201d o \u201c<em>true north\u201d<\/em>. Algunos ejemplos incluyen conversiones (o ventas), crecimiento de ingresos y Net Promoter Score (NPS).<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/pasted-image-0-5.png\"><\/p>\n<p>Si, sin embargo, sientes que necesitas una soluci\u00f3n a medida para tu estrategia GTM, aqu\u00ed va una gu\u00eda exhaustiva sobre c\u00f3mo <a href=\"https:\/\/hackernoon.com\/metrics-game-framework-5e3dce1be8ac\" target=\"_blank\" rel=\"noopener\">desarrollar tus propias m\u00e9tricas de \u00e9xito<\/a>.<\/p>\n<p><strong>Lectura recomendada:<\/strong> <em><a href=\"https:\/\/ahrefs.com\/blog\/es\/metricas-marketing\/\">25 M\u00e9tricas de Marketing que Deber\u00edas Seguir<\/a><\/em><\/p>\n<h2>Reflexiones finales<\/h2>\n<p>Crear una estrategia de go-to-market requiere mucho trabajo y habilidades. Sin embargo, no hay una forma mejor de asegurar el lanzamiento de un nuevo producto. Estar\u00eda dispuesto a apostar que es mejor tener una estrategia GTM \u201cm\u00e1s o menos buena\u201d que ninguna.<\/p>\n<p>As\u00ed que mant\u00e9n la calma y sigue con tu estrategia GTM. Cuando hayas hecho todos los pasos tendr\u00e1s una herramienta que incrementa tus posibilidades de \u00e9xito, adem\u00e1s har\u00e1 que t\u00fa y tus compa\u00f1eros de equipo durm\u00e1is mejor durante el per\u00edodo estresante de un lanzamiento.<\/p>\n<p>\u00bfAlguna pregunta? Escr\u00edbeme <a href=\"https:\/\/twitter.com\/m_makosiewicz?lang=en\" target=\"_blank\" rel=\"noopener\">por Twitter<\/a>.<\/p>\n<p><em>Tra\u00adduci\u00addo por Iv\u00e1n Fanego, creador del primer <\/em><em><a href=\"https:\/\/appcritic.es\/directorio\/\" target=\"_blank\" rel=\"noopener\">directorio de herramientas profesionales de WhatsApp Marketing<\/a><\/em><em>. <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La estrategia de go-to-market(estrategia para salir al mercado) es el m\u00e9todo para darte luz verde para presentar un nuevo producto y hacer cualquier cambio significativo mientras haya tiempo. En este art\u00edculo aprender\u00e1s: Qu\u00e9 es una estrategia go-to-market (GTM) Diferencias entre<span class=\"ellipsis\">\u2026<\/span><\/p>\n<div class=\"read-more\">Leer m\u00e1s \u203a<\/div>\n<p><!-- end of .read-more --><\/p>\n","protected":false},"author":26,"featured_media":9356,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[42],"tags":[],"coauthors":[52],"class_list":["post-9312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing","odd"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo crear una estrategia Go-to-Market en 8 pasos<\/title>\n<meta name=\"description\" content=\"Una estrategia go-to-market (GTM) es el plan de una compa\u00f1\u00eda para traer un nuevo producto o servicio al mercado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo Crear una Estrategia Go-to-Market en 8 Pasos\" \/>\n<meta property=\"og:description\" content=\"Prep\u00e1rate para el lanzamiento de tu producto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de SEO de Ahrefs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ahrefs\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-23T14:43:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-09T17:41:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/fb-go_to_market_strategy-SPA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"990\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mateusz Makosiewicz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@m_makosiewicz\" \/>\n<meta name=\"twitter:site\" content=\"@ahrefs\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/crear-estrategia-go-to-market\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/crear-estrategia-go-to-market\\\/\"},\"author\":{\"name\":\"Mateusz Makosiewicz\",\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/#\\\/schema\\\/person\\\/c6a1d1e44b3ac6b96c39e7d66d021a60\"},\"headline\":\"C\u00f3mo crear una estrategia Go-to-Market en 8&nbsp;pasos\",\"datePublished\":\"2022-01-23T14:43:53+00:00\",\"dateModified\":\"2023-10-09T17:41:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/crear-estrategia-go-to-market\\\/\"},\"wordCount\":5020,\"image\":{\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/crear-estrategia-go-to-market\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/fb-go_to_market_strategy-SPA.png\",\"articleSection\":[\"Marketing general\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/crear-estrategia-go-to-market\\\/\",\"url\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/crear-estrategia-go-to-market\\\/\",\"name\":\"C\u00f3mo crear una estrategia Go-to-Market en 8 pasos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/crear-estrategia-go-to-market\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/crear-estrategia-go-to-market\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/fb-go_to_market_strategy-SPA.png\",\"datePublished\":\"2022-01-23T14:43:53+00:00\",\"dateModified\":\"2023-10-09T17:41:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/#\\\/schema\\\/person\\\/c6a1d1e44b3ac6b96c39e7d66d021a60\"},\"description\":\"Una estrategia go-to-market (GTM) es el plan de una compa\u00f1\u00eda para traer un nuevo producto o servicio al mercado.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/crear-estrategia-go-to-market\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/crear-estrategia-go-to-market\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/fb-go_to_market_strategy-SPA.png\",\"contentUrl\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/fb-go_to_market_strategy-SPA.png\",\"width\":1920,\"height\":990},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/\",\"name\":\"Blog de SEO de Ahrefs\",\"description\":\"Estrategias de link building y consejos de posicionamiento SEO\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/#\\\/schema\\\/person\\\/c6a1d1e44b3ac6b96c39e7d66d021a60\",\"name\":\"Mateusz Makosiewicz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/mateusz-makosiewicz.pngb9dad0367aa6ea69cf3d3b96c68895b4\",\"url\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/mateusz-makosiewicz.png\",\"contentUrl\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/mateusz-makosiewicz.png\",\"caption\":\"Mateusz Makosiewicz\"},\"description\":\"Investigador en marketing y educador en Ahrefs. Mateusz tiene m\u00e1s de 10 a\u00f1os de experiencia en marketing conseguidos en agencias, negocios SaaS (software como servicio) y hardware. Cuando no est\u00e1 escribiendo, est\u00e1 componiendo m\u00fasica o disfrutando de largos paseos.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mateusz-makosiewicz-38154b67\\\/\",\"https:\\\/\\\/x.com\\\/m_makosiewicz\"],\"url\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/author\\\/mateusz-makosiewicz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo crear una estrategia Go-to-Market en 8 pasos","description":"Una estrategia go-to-market (GTM) es el plan de una compa\u00f1\u00eda para traer un nuevo producto o servicio al mercado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo Crear una Estrategia Go-to-Market en 8 Pasos","og_description":"Prep\u00e1rate para el lanzamiento de tu producto.","og_url":"https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/","og_site_name":"Blog de SEO de Ahrefs","article_publisher":"https:\/\/www.facebook.com\/Ahrefs","article_published_time":"2022-01-23T14:43:53+00:00","article_modified_time":"2023-10-09T17:41:36+00:00","og_image":[{"width":1920,"height":990,"url":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/fb-go_to_market_strategy-SPA.png","type":"image\/png"}],"author":"Mateusz Makosiewicz","twitter_card":"summary_large_image","twitter_creator":"@m_makosiewicz","twitter_site":"@ahrefs","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/#article","isPartOf":{"@id":"https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/"},"author":{"name":"Mateusz Makosiewicz","@id":"https:\/\/ahrefs.com\/blog\/es\/#\/schema\/person\/c6a1d1e44b3ac6b96c39e7d66d021a60"},"headline":"C\u00f3mo crear una estrategia Go-to-Market en 8&nbsp;pasos","datePublished":"2022-01-23T14:43:53+00:00","dateModified":"2023-10-09T17:41:36+00:00","mainEntityOfPage":{"@id":"https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/"},"wordCount":5020,"image":{"@id":"https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/#primaryimage"},"thumbnailUrl":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/fb-go_to_market_strategy-SPA.png","articleSection":["Marketing general"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/","url":"https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/","name":"C\u00f3mo crear una estrategia Go-to-Market en 8 pasos","isPartOf":{"@id":"https:\/\/ahrefs.com\/blog\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/#primaryimage"},"image":{"@id":"https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/#primaryimage"},"thumbnailUrl":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/fb-go_to_market_strategy-SPA.png","datePublished":"2022-01-23T14:43:53+00:00","dateModified":"2023-10-09T17:41:36+00:00","author":{"@id":"https:\/\/ahrefs.com\/blog\/es\/#\/schema\/person\/c6a1d1e44b3ac6b96c39e7d66d021a60"},"description":"Una estrategia go-to-market (GTM) es el plan de una compa\u00f1\u00eda para traer un nuevo producto o servicio al mercado.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ahrefs.com\/blog\/es\/crear-estrategia-go-to-market\/#primaryimage","url":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/fb-go_to_market_strategy-SPA.png","contentUrl":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2022\/01\/fb-go_to_market_strategy-SPA.png","width":1920,"height":990},{"@type":"WebSite","@id":"https:\/\/ahrefs.com\/blog\/es\/#website","url":"https:\/\/ahrefs.com\/blog\/es\/","name":"Blog de SEO de Ahrefs","description":"Estrategias de link building y consejos de posicionamiento SEO","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ahrefs.com\/blog\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ahrefs.com\/blog\/es\/#\/schema\/person\/c6a1d1e44b3ac6b96c39e7d66d021a60","name":"Mateusz Makosiewicz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2021\/10\/mateusz-makosiewicz.pngb9dad0367aa6ea69cf3d3b96c68895b4","url":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2021\/10\/mateusz-makosiewicz.png","contentUrl":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2021\/10\/mateusz-makosiewicz.png","caption":"Mateusz Makosiewicz"},"description":"Investigador en marketing y educador en Ahrefs. Mateusz tiene m\u00e1s de 10 a\u00f1os de experiencia en marketing conseguidos en agencias, negocios SaaS (software como servicio) y hardware. Cuando no est\u00e1 escribiendo, est\u00e1 componiendo m\u00fasica o disfrutando de largos paseos.","sameAs":["https:\/\/www.linkedin.com\/in\/mateusz-makosiewicz-38154b67\/","https:\/\/x.com\/m_makosiewicz"],"url":"https:\/\/ahrefs.com\/blog\/es\/author\/mateusz-makosiewicz\/"}]}},"as_json":null,"as_tables":null,"as_images":null,"json_reviewers":[5],"as_coauthors":[],"as_post_info":null,"as_sticky":null,"as_hreflang":null,"_links":{"self":[{"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/posts\/9312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=9312"}],"version-history":[{"count":0,"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/posts\/9312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/media\/9356"}],"wp:attachment":[{"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=9312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=9312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=9312"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/coauthors?post=9312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}