{"id":18008,"date":"2024-12-12T10:26:58","date_gmt":"2024-12-12T18:26:58","guid":{"rendered":"https:\/\/ahrefs.com\/blog\/es\/?p=18008"},"modified":"2024-12-12T10:32:23","modified_gmt":"2024-12-12T18:32:23","slug":"etiquetas-html","status":"publish","type":"post","link":"https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/","title":{"rendered":"Etiquetas HTML: gu\u00eda b\u00e1sica"},"content":{"rendered":"<div class=\"intro-txt\">Este art\u00edculo est\u00e1 pensado para entender bien qu\u00e9 es el HTML y cu\u00e1les son las etiquetas y atributos m\u00e1s importantes de cara al posicionamiento web.<\/div>\n<div class=\"post-nav-link clearfix\" id=\"section1\"><a class=\"subhead-anchor\" data-tip=\"tooltip__copielink\" rel=\"#section1\"><svg width=\"19\" height=\"19\" viewBox=\"0 0 14 14\" style><g fill=\"none\" fill-rule=\"evenodd\"><path d=\"M0 0h14v14H0z\" \/><path d=\"M7.45 9.887l-1.62 1.621c-.92.92-2.418.92-3.338 0a2.364 2.364 0 0 1 0-3.339l1.62-1.62-1.273-1.272-1.62 1.62a4.161 4.161 0 1 0 5.885 5.884l1.62-1.62L7.45 9.886zM5.527 5.135L7.17 3.492c.92-.92 2.418-.92 3.339 0 .92.92.92 2.418 0 3.339L8.866 8.473l1.272 1.273 1.644-1.643A4.161 4.161 0 1 0 5.897 2.22L4.254 3.863l1.272 1.272zm-.66 3.998a.749.749 0 0 1 0-1.06l2.208-2.206a.749.749 0 1 1 1.06 1.06L5.928 9.133a.75.75 0 0 1-1.061 0z\" style \/><\/g><\/svg><\/a><div class=\"link-text\" data-anchor=\"<em>\u00bfQu\u00e9 son las etiquetas HTML?<\/em>\" data-section=\"que-son-etiquetas-html\">\n<h2><strong>\u00bfQu\u00e9 son las etiquetas HTML?<\/strong><\/h2>\n<\/div><\/div>\n<p>HTML (<em>HyperText Markup Language<\/em>) es el lenguaje b\u00e1sico que usamos para estructurar el contenido en la web. Podemos imaginar las etiquetas de HTML como las \u201ccajas\u201d donde colocamos el contenido. Ya sea este texto, im\u00e1genes, v\u00eddeos u otros elementos que pueden componer una p\u00e1gina.<\/p>\n<p>Cada una de estas cajas tiene una funci\u00f3n espec\u00edfica: algunas definen t\u00edtulos <code>(h1)<\/code>, otras describen p\u00e1rrafos (<code>p<\/code>), o bien enlaces (<code>a<\/code>), im\u00e1genes (<code>img<\/code>), entre muchas otras.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-18014\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/1-etiquetas-blog-ahrefs.png\" alt=\"Ejemplo de etiquetas HTML en la p\u00e1gina Home del blog de Ahrefs\" width=\"1788\" height=\"896\" srcset=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/1-etiquetas-blog-ahrefs.png 1788w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/1-etiquetas-blog-ahrefs-680x341.png 680w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/1-etiquetas-blog-ahrefs-768x385.png 768w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/1-etiquetas-blog-ahrefs-1536x770.png 1536w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/1-etiquetas-blog-ahrefs-400x200.png 400w\" sizes=\"auto, (max-width: 1788px) 100vw, 1788px\"><\/p>\n<p>Con el paso del tiempo, se han estandarizado muchas de estas cajas (etiquetas) para que todos los navegadores las interpreten de una forma similar.<\/p>\n<p>Si bien algunas etiquetas de HTML son fundamentales para el SEO, como los encabezados que ayudan a estructurar el contenido, Google ha dejado bien claro que los factores simples, como la mera existencia de estas etiquetas, no son autom\u00e1ticamente se\u00f1ales de ranking en s\u00ed mismos.<\/p>\n<p>Si bien el HTML v\u00e1lido no es un factor de posicionamiento, y utilizar una herramienta de comprobaci\u00f3n de est\u00e1ndares HTML, no servir\u00e1 directamente para mejorar el posicionamiento, s\u00ed hay etiquetas y atributos de HTML que Google tiene en cierta consideraci\u00f3n, y errores de HTML que pueden afectar a la legibilidad de una&nbsp;web.<\/p>\n<div class=\"post-nav-link clearfix\" id=\"section1\"><a class=\"subhead-anchor\" data-tip=\"tooltip__copielink\" rel=\"#section1\"><svg width=\"19\" height=\"19\" viewBox=\"0 0 14 14\" style><g fill=\"none\" fill-rule=\"evenodd\"><path d=\"M0 0h14v14H0z\" \/><path d=\"M7.45 9.887l-1.62 1.621c-.92.92-2.418.92-3.338 0a2.364 2.364 0 0 1 0-3.339l1.62-1.62-1.273-1.272-1.62 1.62a4.161 4.161 0 1 0 5.885 5.884l1.62-1.62L7.45 9.886zM5.527 5.135L7.17 3.492c.92-.92 2.418-.92 3.339 0 .92.92.92 2.418 0 3.339L8.866 8.473l1.272 1.273 1.644-1.643A4.161 4.161 0 1 0 5.897 2.22L4.254 3.863l1.272 1.272zm-.66 3.998a.749.749 0 0 1 0-1.06l2.208-2.206a.749.749 0 1 1 1.06 1.06L5.928 9.133a.75.75 0 0 1-1.061 0z\" style \/><\/g><\/svg><\/a><div class=\"link-text\" data-anchor=\"Partes de una etiqueta HTML\" data-section=\"partes-etiqueta-html\">\n<h2><strong>Partes de una etiqueta HTML<\/strong><\/h2>\n<\/div><\/div>\n<p>Para los que somos t\u00e9cnicos, desglosar una etiqueta HTML es tan b\u00e1sico como necesario, porque aqu\u00ed es donde comienza todo. Cada etiqueta tiene su propio papel y estructura, y conocerla al detalle es esencial para optimizar cualquier p\u00e1gina web. Vamos por partes:<\/p>\n<p><strong>Etiqueta<\/strong>: Esta parte siempre empieza con un s\u00edmbolo \u201c<code>&lt;<\/code>\u201d seguido del nombre de <strong>la etiqueta<\/strong> y puede incluir atributos que le a\u00f1aden propiedades espec\u00edficas. Por ejemplo, en <code><span style=\"font-weight: 400;\">&lt;a href=\"https:\/\/ejemplo.com\"<\/span><\/code>, la etiqueta de apertura es <code>&lt;a&gt;<\/code> y tiene el atributo <strong>href<\/strong>, que define a d\u00f3nde apunta el enlace.<\/p>\n<p>La etiqueta <strong>div <\/strong>es la m\u00e1s com\u00fan y viene de la palabra \u201c<em>division<\/em>\u201d. Sin embargo, distintas etiquetas tienen ciertas propiedades nativas que nos van a ser de gran utilidad.<\/p>\n<p><strong>Contenido<\/strong>: Es lo que va dentro de la etiqueta. En el caso del ejemplo anterior, el contenido ser\u00eda el texto visible en el enlace, como \u201cVis\u00edtanos aqu\u00ed\u201d. No todas las etiquetas tienen contenido visible (por ejemplo, <code>&lt;img&gt;<\/code> no tiene), pero en muchas etiquetas, como las de p\u00e1rrafos o enlaces, el contenido es crucial para el SEO, ya que es lo que los motores de b\u00fasqueda rastrean.<\/p>\n<p><strong>Atributos<\/strong>: Son las instrucciones adicionales que le damos a la etiqueta. Est\u00e1n en la etiqueta de apertura y siguen un formato nombre=\u201cvalor\u201d. Siguiendo con el ejemplo del enlace, el atributo <em>href=\u201chttps:\/\/ejemplo.com\u201d<\/em> le dice al navegador hacia d\u00f3nde debe llevar el enlace. Otros atributos como <em>alt<\/em> en im\u00e1genes o <em>title<\/em> en enlaces tambi\u00e9n pueden mejorar la accesibilidad y el SEO, si se usan correctamente.<\/p>\n<p><strong>Etiqueta de cierre<\/strong>: Cierra la caja. Siempre tiene el mismo nombre que la etiqueta de apertura, pero con una barra diagonal al principio:<code>&lt;a&gt;<\/code>. Sin esta etiqueta de cierre, el navegador no sabr\u00eda cu\u00e1ndo termina el contenido de la caja, lo que puede generar errores en la interpretaci\u00f3n del c\u00f3digo. Hay excepciones, claro, como <code>&lt;img&gt;<\/code>; o <code>&lt;br&gt;<\/code> o nuestras amadas etiquetas <code>&lt;meta&gt;<\/code>, que son etiquetas \u201cautocontenidas\u201d y no necesitan cierre.<\/p>\n<p>Una vez hemos entendido esto, podemos ver algunas etiquetas b\u00e1sicas.<br>\n<\/p><div class=\"post-nav-link clearfix\" id=\"section1\"><a class=\"subhead-anchor\" data-tip=\"tooltip__copielink\" rel=\"#section1\"><svg width=\"19\" height=\"19\" viewBox=\"0 0 14 14\" style><g fill=\"none\" fill-rule=\"evenodd\"><path d=\"M0 0h14v14H0z\" \/><path d=\"M7.45 9.887l-1.62 1.621c-.92.92-2.418.92-3.338 0a2.364 2.364 0 0 1 0-3.339l1.62-1.62-1.273-1.272-1.62 1.62a4.161 4.161 0 1 0 5.885 5.884l1.62-1.62L7.45 9.886zM5.527 5.135L7.17 3.492c.92-.92 2.418-.92 3.339 0 .92.92.92 2.418 0 3.339L8.866 8.473l1.272 1.273 1.644-1.643A4.161 4.161 0 1 0 5.897 2.22L4.254 3.863l1.272 1.272zm-.66 3.998a.749.749 0 0 1 0-1.06l2.208-2.206a.749.749 0 1 1 1.06 1.06L5.928 9.133a.75.75 0 0 1-1.061 0z\" style \/><\/g><\/svg><\/a><div class=\"link-text\" data-anchor=\"\u00bfCu\u00e1les son las etiquetas HTML b\u00e1sicas?\" data-section=\"etiquetas-html-basicas\">\n<h2><strong>\u00bfCu\u00e1les son las etiquetas HTML b\u00e1sicas?<\/strong><\/h2>\n<\/div><\/div>\n<ul>\n<li><strong><strong><code>&lt;head&gt;<\/code><\/strong><strong>: <\/strong><\/strong>Esta etiqueta da la informaci\u00f3n b\u00e1sica sobre la p\u00e1gina. Suelen ser elementos no visibles, pero que indican archivos necesarios para la visualizaci\u00f3n de la p\u00e1gina y las metaetiquetas. Una metaetiqueta, como su nombre indica, es una etiqueta que habla sobre la propia p\u00e1gina en s\u00ed&nbsp;misma.<\/li>\n<\/ul>\n<ul>\n<li><strong><code>&lt;body&gt;<\/code><\/strong><strong>: <\/strong>Esta etiqueta es donde debe poner todo el contenido principal de una&nbsp;web.<\/li>\n<\/ul>\n<ul>\n<li><strong><code>footer<\/code><\/strong><strong>: <\/strong>Aqu\u00ed es donde deberemos colocar toda la informaci\u00f3n que pongamos en el pie de p\u00e1gina.<\/li>\n<\/ul>\n<ul>\n<li><strong><code>header<\/code>: <\/strong>Corresponde al encabezado visual de una p\u00e1gina web. Aqu\u00ed se suelen poner elementos como la barra de navegaci\u00f3n, y esta etiqueta debe ir dentro del&nbsp;body.<\/li>\n<\/ul>\n<ul>\n<li><strong><code>div<\/code>: <\/strong>Es la etiqueta m\u00e1s com\u00fan, aunque el est\u00e1ndar de HTML pide que se utilicen otras etiquetas como &lt;code&gt;&lt;section&gt;&lt;\/code&gt; o &lt;code&gt;&lt;article&gt;&lt;\/code&gt; para evitar utilizar <em>div<\/em> para todo. Sirve para dividir el contenido como su nombre indica.<\/li>\n<\/ul>\n<ul>\n<li><strong><code>span<\/code>: <\/strong>La diferencia principal entre <em>div<\/em> y <em>span<\/em>. Es que cuando t\u00fa pones contenido en una etiqueta <em>div<\/em>. Esa \u201ccaja\u201d se genera autom\u00e1ticamente y forma un espacio f\u00edsico. El <em>span<\/em> por defecto no. As\u00ed que el <em>span<\/em> sirve principalmente para seleccionar alguna frase o palabra dentro de un elemento y destacarlo con estilos CSS.<\/li>\n<\/ul>\n<ul>\n<li><strong><code>p<\/code>: <\/strong>Es la etiqueta que indica un p\u00e1rrafo de texto y es bastante \u00fatil para dividir distintos p\u00e1rrafos de&nbsp;texto.<\/li>\n<\/ul>\n<ul>\n<li><strong><code>b<\/code>: <\/strong>Tanto <em>b<\/em> como <em>strong<\/em> son etiquetas para hacer negrita un texto. Si alguna vez te lo has preguntado. <a href=\"https:\/\/www.youtube.com\/watch?v=awto_wCeOJ4\">Para Google ambas tienen el mismo efecto<\/a>.<\/li>\n<\/ul>\n<div id=\"attachment_18015\" style=\"width: 910px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-18015\" class=\"wp-image-18015 size-full\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/2-etiquetas-html-post.png\" alt=\"Etiquetas HTML en un post de Ahrefs\" width=\"900\" height=\"826\" srcset=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/2-etiquetas-html-post.png 900w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/2-etiquetas-html-post-463x425.png 463w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/2-etiquetas-html-post-768x705.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\"><p id=\"caption-attachment-18015\" class=\"wp-caption-text\">Ejemplo de un HTML de una web b\u00e1sico<\/p><\/div>\n<div class=\"post-nav-link clearfix\" id=\"section1\"><a class=\"subhead-anchor\" data-tip=\"tooltip__copielink\" rel=\"#section1\"><svg width=\"19\" height=\"19\" viewBox=\"0 0 14 14\" style><g fill=\"none\" fill-rule=\"evenodd\"><path d=\"M0 0h14v14H0z\" \/><path d=\"M7.45 9.887l-1.62 1.621c-.92.92-2.418.92-3.338 0a2.364 2.364 0 0 1 0-3.339l1.62-1.62-1.273-1.272-1.62 1.62a4.161 4.161 0 1 0 5.885 5.884l1.62-1.62L7.45 9.886zM5.527 5.135L7.17 3.492c.92-.92 2.418-.92 3.339 0 .92.92.92 2.418 0 3.339L8.866 8.473l1.272 1.273 1.644-1.643A4.161 4.161 0 1 0 5.897 2.22L4.254 3.863l1.272 1.272zm-.66 3.998a.749.749 0 0 1 0-1.06l2.208-2.206a.749.749 0 1 1 1.06 1.06L5.928 9.133a.75.75 0 0 1-1.061 0z\" style \/><\/g><\/svg><\/a><div class=\"link-text\" data-anchor=\"Etiquetas HTML para SEO\" data-section=\"etiquetas-html-para-seo\">\n<h2><strong>Etiquetas HTML para&nbsp;SEO<\/strong><\/h2>\n<\/div><\/div>\n<p>Hay ciertas etiquetas de HTML que debemos tener en cuenta de cara al posicionamiento web.<\/p>\n<h3>Meta Viewport<\/h3>\n<p>La etiqueta <code>&lt;meta name=\"viewport\"&gt;<\/code> se usa para controlar c\u00f3mo el contenido se adapta a diferentes dispositivos. Es fundamental para la optimizaci\u00f3n m\u00f3vil, ya que ayuda a garantizar que el sitio sea \u201cresponsive\u201d, ajustando el tama\u00f1o y la escala en dispositivos m\u00f3viles.<br>\nGoogle prioriza los sitios optimizados para m\u00f3viles en sus rankings, especialmente desde que se implement\u00f3 el \u201cMobile-First Indexing\u201d. Un mal uso de la meta viewport podr\u00eda resultar en una mala experiencia de usuario, lo que afecta negativamente al&nbsp;SEO.<\/p>\n<h3>Metaetiquetas<\/h3>\n<p>Las metaetiquetas <code>&lt;meta&gt;<\/code> en combinaci\u00f3n con atributos como <code>name=\"robots\"<\/code>, <code>name=\"description\"<\/code>o incluso los Open Graph juegan un papel crucial. Ya que nos permite jugar con la indexaci\u00f3n y visualizaci\u00f3n de nuestro contenido en las&nbsp;SERP.<br>\nEstas etiquetas se encargan siempre de describir caracter\u00edsticas de esa propia p\u00e1gina.<br>\nAlgunas nos permiten incluso emular respuestas de servidor o indicar la URL canon (canonical) de una versi\u00f3n distinta de la&nbsp;URL.<\/p>\n<h3><em>Headings<\/em><\/h3>\n<p>Las etiquetas<code>&lt;h1&gt;<\/code>, <code>&lt;h2&gt;<\/code>,<code>&lt;h3&gt;<\/code> etc., estructuran el contenido de una p\u00e1gina jer\u00e1rquicamente. El <code>&lt;h1&gt;<\/code> es el t\u00edtulo principal de la p\u00e1gina, mientras que las etiquetas subsecuentes (&lt;h2&gt;, &lt;h3&gt;, etc.) agrupan secciones importantes.<\/p>\n<h3><em>Summary details<\/em><\/h3>\n<p>Las etiquetas <code>&lt;summary&gt;<\/code> y <code>&lt;details&gt;<\/code> permiten ocultar y mostrar informaci\u00f3n adicional cuando el usuario interact\u00faa. Son \u00fatiles para mostrar contenido opcional de manera m\u00e1s ordenada.<\/p>\n<p>Sin necesidad de utilizar JavaScript nos permite mostrar contenido en modo acorde\u00f3n, como preguntas frecuentes y asegura que Google y otros motores de b\u00fasqueda puedan encontrar estas etiquetas.<\/p>\n<h3>Tablas y listados<\/h3>\n<p>Las tablas (<code>&lt;table&gt;<\/code> y listados (<code>&lt;ul&gt;<\/code>, <code>&lt;ol&gt;<\/code>, <code>&lt;li&gt;<\/code>) estructuran el contenido de manera l\u00f3gica.<\/p>\n<p>Los motores de b\u00fasqueda prefieren contenido estructurado de forma clara. Las listas y tablas bien etiquetadas facilitan el an\u00e1lisis de contenido y, de hecho Google podr\u00eda destacarlos como fragmentos enriquecidos (<em>rich snippets<\/em>).<\/p>\n<h3>Nav<\/h3>\n<p>La etiqueta &lt;nav&gt; indica la secci\u00f3n de navegaci\u00f3n de un sitio web, generalmente utilizada para los men\u00fas principales.<\/p>\n<p>Una estructura de navegaci\u00f3n clara mejora la experiencia del usuario y facilita que los motores de b\u00fasqueda rastreen e indexen las p\u00e1ginas importantes del sitio. Ayuda a mejorar la \u201ccrawlability\u201d y la arquitectura del&nbsp;sitio.<\/p>\n<h3>Iframes<\/h3>\n<p>Los<em> Iframes<\/em> nos sirven para mostrar v\u00eddeos o contenido externo en nuestra web. Lo cual puede ser muy potente si se combinan con t\u00e9cnicas de carga diferida (como loading=\u201dlazy\u201d o \u201cloads on interactions\u201d) o si se muestran directamente ayudados de una correcta implementaci\u00f3n de la metaetiqueta <em>indexifembedded<\/em>.<\/p>\n<h3>IMG<\/h3>\n<p>La etiqueta <code>&lt;img&gt;<\/code> se usa para incluir im\u00e1genes en el contenido. Es importante utilizar atributos como <em>alt<\/em> y <em>title<\/em> para describir la imagen.<\/p>\n<p>Las im\u00e1genes bien optimizadas, con atributos <em>alt<\/em> descriptivos, ayudan a los motores de b\u00fasqueda a entender el contenido de la imagen. Esto es especialmente importante para la b\u00fasqueda de im\u00e1genes y la accesibilidad. Adem\u00e1s, el uso correcto del atributo<em> alt<\/em> puede mejorar el ranking de una p\u00e1gina si las palabras clave est\u00e1n bien integradas en la descripci\u00f3n.<\/p>\n<h3>Picture<\/h3>\n<p>La etiqueta <code>&lt;picture&gt;<\/code> no solo permite servir im\u00e1genes de diferentes resoluciones seg\u00fan las caracter\u00edsticas del dispositivo, sino que tambi\u00e9n facilita la entrega de distintos formatos de imagen.<\/p>\n<p>Esto es especialmente relevante cuando se trata de optimizar la carga y el rendimiento del sitio web, ya que algunos formatos de imagen, como WebP o AVIF, son mucho m\u00e1s eficientes que los tradicionales como JPEG o PNG, pero no todos los navegadores los procesan de forma correcta.<br>\n<\/p><div class=\"post-nav-link clearfix\" id=\"section1\"><a class=\"subhead-anchor\" data-tip=\"tooltip__copielink\" rel=\"#section1\"><svg width=\"19\" height=\"19\" viewBox=\"0 0 14 14\" style><g fill=\"none\" fill-rule=\"evenodd\"><path d=\"M0 0h14v14H0z\" \/><path d=\"M7.45 9.887l-1.62 1.621c-.92.92-2.418.92-3.338 0a2.364 2.364 0 0 1 0-3.339l1.62-1.62-1.273-1.272-1.62 1.62a4.161 4.161 0 1 0 5.885 5.884l1.62-1.62L7.45 9.886zM5.527 5.135L7.17 3.492c.92-.92 2.418-.92 3.339 0 .92.92.92 2.418 0 3.339L8.866 8.473l1.272 1.273 1.644-1.643A4.161 4.161 0 1 0 5.897 2.22L4.254 3.863l1.272 1.272zm-.66 3.998a.749.749 0 0 1 0-1.06l2.208-2.206a.749.749 0 1 1 1.06 1.06L5.928 9.133a.75.75 0 0 1-1.061 0z\" style \/><\/g><\/svg><\/a><div class=\"link-text\" data-anchor=\"Atributos de HTML interesantes para SEO\" data-section=\"atributos-html-interesantes-para-seo\">\n<h2><strong>Atributos de HTML interesantes para&nbsp;SEO<\/strong><\/h2>\n<\/div><\/div>\n<h3>data-nosnippet<\/h3>\n<p>Evita que ciertos fragmentos de contenido se muestren en los resultados de b\u00fasqueda. Puede ser \u00fatil para controlar qu\u00e9 partes de tu p\u00e1gina aparecen en el snippet de Google.<br>\nSi quieres evitar que contenidos como CTA o el banner de Cookies aparezcan en tus SERP es una buena opci\u00f3n para implementar en etiquetas <em>div<\/em>, <em>span<\/em> o <em>section<\/em>. Que son las que Google reconoce.<\/p>\n<h3>loading=\u201clazy\u201d<\/h3>\n<p>Carga im\u00e1genes o <em>iframes <\/em>solo cuando est\u00e1n a punto de ser visibles en la pantalla, lo que mejora los tiempos de carga iniciales.<br>\nMejora la velocidad de la p\u00e1gina, afectando positivamente los Core Web Vitals, lo que es un factor de ranking importante. Aunque no se debe abusar y solo se debe poner en contenido que no se muestra en el viewport.<\/p>\n<h3>rel<\/h3>\n<p>Mediante el uso de <em>nofollow<\/em>, <em>ugc<\/em> o <em>sponsored<\/em> controlamos si Google debe o no seguir dichos enlaces en una etiqueta a.<\/p>\n<h3><em>Async<\/em> y <em>Defer<\/em><\/h3>\n<p>Optimizan la carga de scripts de JavaScript:<\/p>\n<ul>\n<li><strong>defer<\/strong>: Retrasa la ejecuci\u00f3n del script hasta que el HTML est\u00e9 completamente cargado.<\/li>\n<li><strong>async<\/strong>: Ejecuta el script en paralelo con el resto de la p\u00e1gina.<\/li>\n<\/ul>\n<p>En definitiva, bien empleados mejoran los tiempos de carga, lo que puede influir en el ranking de Google al mejorar la experiencia del usuario y los Core Web Vitals.<\/p>\n<h3>Atributo ALT<\/h3>\n<p>Proporciona una descripci\u00f3n textual para im\u00e1genes, utilizado por los motores de b\u00fasqueda y para la accesibilidad. Es la forma que tienen los motores de b\u00fasqueda de entender el contenido de la imagen y permitirnos tener un mejor posicionamiento en los buscadores de im\u00e1genes.<br>\n<\/p><div class=\"post-nav-link clearfix\" id=\"section1\"><a class=\"subhead-anchor\" data-tip=\"tooltip__copielink\" rel=\"#section1\"><svg width=\"19\" height=\"19\" viewBox=\"0 0 14 14\" style><g fill=\"none\" fill-rule=\"evenodd\"><path d=\"M0 0h14v14H0z\" \/><path d=\"M7.45 9.887l-1.62 1.621c-.92.92-2.418.92-3.338 0a2.364 2.364 0 0 1 0-3.339l1.62-1.62-1.273-1.272-1.62 1.62a4.161 4.161 0 1 0 5.885 5.884l1.62-1.62L7.45 9.886zM5.527 5.135L7.17 3.492c.92-.92 2.418-.92 3.339 0 .92.92.92 2.418 0 3.339L8.866 8.473l1.272 1.273 1.644-1.643A4.161 4.161 0 1 0 5.897 2.22L4.254 3.863l1.272 1.272zm-.66 3.998a.749.749 0 0 1 0-1.06l2.208-2.206a.749.749 0 1 1 1.06 1.06L5.928 9.133a.75.75 0 0 1-1.061 0z\" style \/><\/g><\/svg><\/a><div class=\"link-text\" data-anchor=\"C\u00f3mo analizar las etiquetas HTML\" data-section=\"como-analizar-etiquetas-html\">\n<h2><strong>C\u00f3mo analizar las etiquetas HTML<\/strong><\/h2>\n<\/div><\/div>\nPara poder ver qu\u00e9 etiquetado de HTML tiene tu p\u00e1gina web hay varias v\u00edas y, cada una de ellas, puede tener utilidades distintas.\n<h3>Navegador web<\/h3>\n<p>Puedes emplear tu navegador web para comprobar qu\u00e9 etiquetado de HTML tiene una web. Como hay gran cantidad de exploradores, voy a explicar los ejemplos con <strong>Google Chrome<\/strong>, que es el navegador m\u00e1s com\u00fan. Aunque en la mayor\u00eda se hace de la misma&nbsp;forma.<\/p>\n<h3>Source<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-18016\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/3-ejemplo-view-source.png\" alt=\"Ejemplo de view-source en una p\u00e1gina web\" width=\"1920\" height=\"569\" srcset=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/3-ejemplo-view-source.png 1920w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/3-ejemplo-view-source-680x202.png 680w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/3-ejemplo-view-source-768x228.png 768w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/3-ejemplo-view-source-1536x455.png 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\"><\/p>\n<p>Puedes ver la fuente original del HTML de tu p\u00e1gina a\u00f1adiendo view-source: delante de una URL. Por ejemplo:<br>\n<code>view-source:https:\/\/ahrefs.com\/blog\/es\/<\/code><\/p>\n<p>O haciendo uso del atajo de teclado Control + U (O clic derecho &gt; Ver c\u00f3digo fuente de la p\u00e1gina) para ver esta informaci\u00f3n.<\/p>\n<p>Este m\u00e9todo nos permite ver c\u00f3mo es el c\u00f3digo que llega a nuestro navegador antes de que JavaScript realice cambios en el DOM (b\u00e1sicamente antes de que JavaScript cambie el c\u00f3digo que hay dentro de la&nbsp;web).<\/p>\n<p>Esto nos permite ver qu\u00e9 contenido hay antes del renderizado, pero Google renderiza JavaScript, por lo que esta forma de analizarlo, aunque relativamente c\u00f3moda a veces, dependiendo de la tecnolog\u00eda de la web, puede ser incompleta.<\/p>\n<p>Pero te permite ver m\u00e1s o menos qu\u00e9 tipo de web es incluso desde el&nbsp;m\u00f3vil.<\/p>\n<h3>Devtools<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-18017\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/4-devtools.png\" alt=\"Ejemplo de uso de Devtools para ver las etiquetas HTML de una p\u00e1gina web\" width=\"1584\" height=\"714\" srcset=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/4-devtools.png 1584w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/4-devtools-680x307.png 680w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/4-devtools-768x346.png 768w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/4-devtools-1536x692.png 1536w\" sizes=\"auto, (max-width: 1584px) 100vw, 1584px\"><\/p>\n<p>Es una forma m\u00e1s avanzada de ver el HTML de una p\u00e1gina. El c\u00f3digo que vemos aqu\u00ed es el c\u00f3digo despu\u00e9s de que act\u00fae JavaScript y ser\u00eda el c\u00f3digo resultante y procesado que acaba viendo tanto Google como los usuarios.<\/p>\n<p>Es una herramienta que todos tenemos habilitados por defecto en nuestro navegador salvo en Mac que est\u00e1 oculto.<\/p>\n<p>Podemos verlo con f12; con Control + May\u00fas + I; o con Control + May\u00fas + C; o con <strong>Clic derecho &gt; Inspeccionar<\/strong>.<\/p>\n<p>En el caso de <strong>Mac<\/strong> tendremos que darle a M\u00e1s ajustes &gt; Herramientas de desarrolladores:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-18018\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/5-developer-tools.png\" alt=\"Opci\u00f3n de Developer Tools en Google Chrome\" width=\"531\" height=\"430\" srcset=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/5-developer-tools.png 531w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/5-developer-tools-525x425.png 525w\" sizes=\"auto, (max-width: 531px) 100vw, 531px\"><\/p>\n<p>Y el atajo de teclado en este caso ser\u00eda Option + \u2318 +&nbsp;I<\/p>\n<p>Lo bueno de esto, es que si pulsamos la flechita de arriba a la izquierda, podremos seleccionar el elemento de HTML que queramos de forma visual.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-18019\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/6-inspeccion-visual-devtools.png\" alt=\"Inspecci\u00f3n visual en DevTools de Chrome\" width=\"1300\" height=\"574\" srcset=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/6-inspeccion-visual-devtools.png 1300w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/6-inspeccion-visual-devtools-680x300.png 680w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/6-inspeccion-visual-devtools-768x339.png 768w\" sizes=\"auto, (max-width: 1300px) 100vw, 1300px\"><\/p>\n<p>De hecho, con esta herramienta podemos modificar el HTML para ver c\u00f3mo quedar\u00eda el contenido:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-18020\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/7-edicion-html.jpg\" alt=\"Ejemplo de edici\u00f3n de HTML en DevTools\" width=\"1765\" height=\"903\" srcset=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/7-edicion-html.jpg 1765w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/7-edicion-html-680x348.jpg 680w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/7-edicion-html-768x393.jpg 768w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/7-edicion-html-1536x786.jpg 1536w\" sizes=\"auto, (max-width: 1765px) 100vw, 1765px\"><\/p>\n<h3>ahrefs<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-18021\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/8-page-inspect-ahrefs.png\" alt=\"An\u00e1lisis de una p\u00e1gina web en Page Inspect de Ahrefs\" width=\"1887\" height=\"902\" srcset=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/8-page-inspect-ahrefs.png 1887w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/8-page-inspect-ahrefs-680x325.png 680w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/8-page-inspect-ahrefs-768x367.png 768w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/8-page-inspect-ahrefs-1536x734.png 1536w\" sizes=\"auto, (max-width: 1887px) 100vw, 1887px\"><\/p>\n<p>Con la funci\u00f3n de <a href=\"https:\/\/ahrefs.com\/academy\/how-to-use-ahrefs\/site-explorer\/page-inspect\">Page Inspect<\/a> de Ahrefs, no solo podemos ver el HTML de cualquier p\u00e1gina que hayamos analizado, sino tambi\u00e9n todo su historial de cambios. Esto resulta perfecto para ver si los cambios que pedimos a un desarrollador fueron realmente implementados.<\/p>\n<p>Tambi\u00e9n podemos analizar de esta forma si hubo evoluci\u00f3n o decrecimiento bas\u00e1ndonos en cambios en el HTML de nuestra web.<\/p>\n<h3>Search Console<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-18022\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/9-gsc-html.png\" alt=\"An\u00e1lisis de etiquetas HTML en Google Search Console\" width=\"514\" height=\"726\" srcset=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/9-gsc-html.png 514w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/9-gsc-html-301x425.png 301w\" sizes=\"auto, (max-width: 514px) 100vw, 514px\"><\/p>\n<p>Si vamos al inspector de p\u00e1ginas de Search Console. Podemos analizar el HTML del \u00faltimo rastreo que hizo Google e incluso probarlo en tiempo real.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-18023\" src=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/10-inspeccion-urls.png\" alt=\"Inspecci\u00f3n de URLs en Google Search Console\" width=\"1319\" height=\"362\" srcset=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/10-inspeccion-urls.png 1319w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/10-inspeccion-urls-680x187.png 680w, https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/10-inspeccion-urls-768x211.png 768w\" sizes=\"auto, (max-width: 1319px) 100vw, 1319px\"><\/p>\n<p>Esto nos permite no solo ver el HTML renderizado de nuestra web, tambi\u00e9n nos permite saber c\u00f3mo lo est\u00e1 viendo Google.<\/p>\n<h3>Buscadores de&nbsp;HTML<\/h3>\n<p>Si queremos ver c\u00f3mo funciona una etiqueta de HTML o un atributo en una web, podemos buscar una web que lo contenga con un buscador de HTML como PublicWWW o nerdydata, especialmente si nos ayudamos de <a href=\"https:\/\/ahrefs.com\/blog\/es\/patrones-mejorar-seo\/\">regex<\/a>.<\/p>\n<h2>Reflexiones finales<\/h2>\n<p>El HTML son las cajitas o etiquetas donde introducimos todo el contenido que queremos mostrar en una p\u00e1gina. Los navegadores interpretan esto y junto con el CSS, el navegador acaba mostr\u00e1ndonos una imagen de la web que es lo que vemos los usuarios. Si bien se le suele dar una gran importancia a los datos estructurados para que Google entienda el contenido de nuestra p\u00e1gina, realmente la base para que nuestro contenido sea entendible por los motores de b\u00fasqueda es un correcto uso del etiquetado de HTML en nuestra web.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>HTML (HyperText Markup Language) es el lenguaje b\u00e1sico que usamos para estructurar el contenido en la web. Podemos imaginar las etiquetas de HTML como las \u201ccajas\u201d donde colocamos el contenido. Ya sea este texto, im\u00e1genes, v\u00eddeos u otros elementos que<span class=\"ellipsis\">\u2026<\/span><\/p>\n<div class=\"read-more\">Leer m\u00e1s \u203a<\/div>\n<p><!-- end of .read-more --><\/p>\n","protected":false},"author":50,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wp_typography_post_enhancements_disabled":false,"footnotes":""},"categories":[9],"tags":[],"coauthors":[82],"class_list":["post-18008","post","type-post","status-publish","format-standard","hentry","category-technical-seo","odd"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Etiquetas HTML: gu\u00eda b\u00e1sica<\/title>\n<meta name=\"description\" content=\"En esta gu\u00eda aprender\u00e1s todo sobre las etiquetas HTML. Descubre qu\u00e9 son, cu\u00e1les son las m\u00e1s comunes y como aprovecharlas para tu estrategia SEO.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Etiquetas HTML: gu\u00eda b\u00e1sica\" \/>\n<meta property=\"og:description\" content=\"En esta gu\u00eda aprender\u00e1s todo sobre las etiquetas HTML. Descubre qu\u00e9 son, cu\u00e1les son las m\u00e1s comunes y como aprovecharlas para tu estrategia SEO.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de SEO de Ahrefs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ahrefs\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-12T18:26:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-12T18:32:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/1-etiquetas-blog-ahrefs.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1788\" \/>\n\t<meta property=\"og:image:height\" content=\"896\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Carlos Sanchez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ahrefs\" \/>\n<meta name=\"twitter:site\" content=\"@ahrefs\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/etiquetas-html\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/etiquetas-html\\\/\"},\"author\":{\"name\":\"Carlos Sanchez\",\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/#\\\/schema\\\/person\\\/8f252ed97fbdff6752fd0d771fcdef0b\"},\"headline\":\"Etiquetas HTML: gu\u00eda b\u00e1sica\",\"datePublished\":\"2024-12-12T18:26:58+00:00\",\"dateModified\":\"2024-12-12T18:32:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/etiquetas-html\\\/\"},\"wordCount\":2504,\"image\":{\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/etiquetas-html\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/etiquetas-html-guia-basica-by-carlos-sanchez-technical-seo.jpg\",\"articleSection\":[\"SEO T\u00e9cnico\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/etiquetas-html\\\/\",\"url\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/etiquetas-html\\\/\",\"name\":\"Etiquetas HTML: gu\u00eda b\u00e1sica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/etiquetas-html\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/etiquetas-html\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/1-etiquetas-blog-ahrefs.png\",\"datePublished\":\"2024-12-12T18:26:58+00:00\",\"dateModified\":\"2024-12-12T18:32:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/#\\\/schema\\\/person\\\/8f252ed97fbdff6752fd0d771fcdef0b\"},\"description\":\"En esta gu\u00eda aprender\u00e1s todo sobre las etiquetas HTML. Descubre qu\u00e9 son, cu\u00e1les son las m\u00e1s comunes y como aprovecharlas para tu estrategia SEO.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/etiquetas-html\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/etiquetas-html\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/1-etiquetas-blog-ahrefs.png\",\"contentUrl\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/1-etiquetas-blog-ahrefs.png\",\"width\":1788,\"height\":896,\"caption\":\"Ejemplo de etiquetas HTML en la p\u00e1gina Home del blog de Ahrefs\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/\",\"name\":\"Blog de SEO de Ahrefs\",\"description\":\"Estrategias de link building y consejos de posicionamiento SEO\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/#\\\/schema\\\/person\\\/8f252ed97fbdff6752fd0d771fcdef0b\",\"name\":\"Carlos Sanchez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/carlos-sanchez-cara.jpg7829a97e0c6ddee1bd16fa28762b9c20\",\"url\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/carlos-sanchez-cara.jpg\",\"contentUrl\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/carlos-sanchez-cara.jpg\",\"caption\":\"Carlos Sanchez\"},\"url\":\"https:\\\/\\\/ahrefs.com\\\/blog\\\/es\\\/author\\\/carlos-sanchez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Etiquetas HTML: gu\u00eda b\u00e1sica","description":"En esta gu\u00eda aprender\u00e1s todo sobre las etiquetas HTML. Descubre qu\u00e9 son, cu\u00e1les son las m\u00e1s comunes y como aprovecharlas para tu estrategia SEO.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/","og_locale":"es_ES","og_type":"article","og_title":"Etiquetas HTML: gu\u00eda b\u00e1sica","og_description":"En esta gu\u00eda aprender\u00e1s todo sobre las etiquetas HTML. Descubre qu\u00e9 son, cu\u00e1les son las m\u00e1s comunes y como aprovecharlas para tu estrategia SEO.","og_url":"https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/","og_site_name":"Blog de SEO de Ahrefs","article_publisher":"https:\/\/www.facebook.com\/Ahrefs","article_published_time":"2024-12-12T18:26:58+00:00","article_modified_time":"2024-12-12T18:32:23+00:00","og_image":[{"width":1788,"height":896,"url":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/1-etiquetas-blog-ahrefs.png","type":"image\/png"}],"author":"Carlos Sanchez","twitter_card":"summary_large_image","twitter_creator":"@ahrefs","twitter_site":"@ahrefs","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/#article","isPartOf":{"@id":"https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/"},"author":{"name":"Carlos Sanchez","@id":"https:\/\/ahrefs.com\/blog\/es\/#\/schema\/person\/8f252ed97fbdff6752fd0d771fcdef0b"},"headline":"Etiquetas HTML: gu\u00eda b\u00e1sica","datePublished":"2024-12-12T18:26:58+00:00","dateModified":"2024-12-12T18:32:23+00:00","mainEntityOfPage":{"@id":"https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/"},"wordCount":2504,"image":{"@id":"https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/#primaryimage"},"thumbnailUrl":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/etiquetas-html-guia-basica-by-carlos-sanchez-technical-seo.jpg","articleSection":["SEO T\u00e9cnico"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/","url":"https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/","name":"Etiquetas HTML: gu\u00eda b\u00e1sica","isPartOf":{"@id":"https:\/\/ahrefs.com\/blog\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/#primaryimage"},"image":{"@id":"https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/#primaryimage"},"thumbnailUrl":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/1-etiquetas-blog-ahrefs.png","datePublished":"2024-12-12T18:26:58+00:00","dateModified":"2024-12-12T18:32:23+00:00","author":{"@id":"https:\/\/ahrefs.com\/blog\/es\/#\/schema\/person\/8f252ed97fbdff6752fd0d771fcdef0b"},"description":"En esta gu\u00eda aprender\u00e1s todo sobre las etiquetas HTML. Descubre qu\u00e9 son, cu\u00e1les son las m\u00e1s comunes y como aprovecharlas para tu estrategia SEO.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ahrefs.com\/blog\/es\/etiquetas-html\/#primaryimage","url":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/1-etiquetas-blog-ahrefs.png","contentUrl":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/12\/1-etiquetas-blog-ahrefs.png","width":1788,"height":896,"caption":"Ejemplo de etiquetas HTML en la p\u00e1gina Home del blog de Ahrefs"},{"@type":"WebSite","@id":"https:\/\/ahrefs.com\/blog\/es\/#website","url":"https:\/\/ahrefs.com\/blog\/es\/","name":"Blog de SEO de Ahrefs","description":"Estrategias de link building y consejos de posicionamiento SEO","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ahrefs.com\/blog\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ahrefs.com\/blog\/es\/#\/schema\/person\/8f252ed97fbdff6752fd0d771fcdef0b","name":"Carlos Sanchez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/07\/carlos-sanchez-cara.jpg7829a97e0c6ddee1bd16fa28762b9c20","url":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/07\/carlos-sanchez-cara.jpg","contentUrl":"https:\/\/ahrefs.com\/blog\/es\/wp-content\/uploads\/2024\/07\/carlos-sanchez-cara.jpg","caption":"Carlos Sanchez"},"url":"https:\/\/ahrefs.com\/blog\/es\/author\/carlos-sanchez\/"}]}},"as_json":null,"json_reviewers":[30],"_links":{"self":[{"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/posts\/18008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=18008"}],"version-history":[{"count":0,"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/posts\/18008\/revisions"}],"wp:attachment":[{"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=18008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=18008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=18008"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/ahrefs.com\/blog\/es\/wp-json\/wp\/v2\/coauthors?post=18008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}